{"id":221,"date":"2025-02-16T14:14:36","date_gmt":"2025-02-16T14:14:36","guid":{"rendered":"https:\/\/ptifa.com\/?page_id=221"},"modified":"2025-11-03T19:35:22","modified_gmt":"2025-11-03T19:35:22","slug":"a-propos-de","status":"publish","type":"page","link":"https:\/\/ptifa.com\/fr\/about\/","title":{"rendered":"\u00c0 propos"},"content":{"rendered":"<div class=\"gb-element-2e3df423\">\n<div class=\"gb-element-50e136ab  grid-container\">\n<div class=\"gb-element-58fcb580 breadcrumb-row\"><span><span><a href=\"https:\/\/ptifa.com\/fr\/\">Accueil<\/a><\/span><\/span>\n<\/div>\n\n\n\n<div class=\"gb-element-fb322c90\">\n<div class=\"gb-element-4363ee0f breadcrumb-row\">\n<h1 class=\"gb-text gb-text-82a603a2\">\u00c0 propos<\/h1>\n\n\n\n<p class=\"gb-text gb-text-66ea7cab\">Depuis 2008, PTIFAT est \u00e0 la pointe de l'industrie en mati\u00e8re de formation au Botox\u00ae bas\u00e9e sur l'anatomie pour les professionnels des soins dentaires, m\u00e9dicaux et infirmiers.<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-93df6583\">\n<img loading=\"lazy\" decoding=\"async\" width=\"44\" height=\"94\" class=\"gb-media-b8f625a0\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/section-icon.svg\" title=\"ic\u00f4ne de section\"\/>\n\n\n\n<div class=\"wf_video-container\">\n<div class=\"wf_video_cover\">\n<div class=\"wf_video_cover_header\">\n\u00c0 propos de PTIFAT\n<\/div>\n  <button class=\"wf_play-button\" onclick=\"playVideo()\"><img decoding=\"async\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/04\/play.webp\" alt=\"Jouer\" \/> <\/button>\n<div class=\"wf_video_cover_footer\">\n<span>Vid\u00e9o : d\u00e9couvrez ce qui fait de PTIFAT un leader dans le domaine du Botox<\/span>\n<\/div>\n<\/div>\n  <video id=\"wf_video\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/the_importance_of_knowing_both_the_therapeutic__aesthetic_applications_of_botulinum_toxin-720p.mp4\" poster=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/video-poster-image-1.webp\" preload=\"none\">\n    Votre navigateur ne prend pas en charge la balise vid\u00e9o.\n  <\/video>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-1de28abb\">\n<div class=\"gb-element-5c1c8272  grid-container\">\n<div class=\"gb-element-fe5fcd64\">\n<div class=\"gb-element-db2513e6 breadcrumb-row\">\n<div class=\"gb-element-0fff5157\">\n<img loading=\"lazy\" decoding=\"async\" width=\"125\" height=\"62\" class=\"gb-media-c924ea92\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/de-8.000-1.svg\" title=\"+8,000\"\/>\n\n\n\n<p class=\"gb-text gb-text-6a1ca0e8\">Dipl\u00f4m\u00e9s<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-19193f1a\">\n<img loading=\"lazy\" decoding=\"async\" width=\"83\" height=\"57\" class=\"gb-media-adf5e832\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/de-17-1.svg\" title=\"+17\"\/>\n\n\n\n<p class=\"gb-text gb-text-eb1309a5\"><strong>ans<\/strong> \u00e0 la pointe du <br>secteur<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-02c46e7d\">\n<img loading=\"lazy\" decoding=\"async\" width=\"86\" height=\"59\" class=\"gb-media-fc397a42\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/de-16-1.svg\" title=\"+16\"\/>\n\n\n\n<p class=\"gb-text gb-text-c3d7322d\"><strong>heures <\/strong>bas\u00e9 sur l'anatomie<br>en anatomie<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-a0d706db\">\n<div class=\"gb-element-4389e4cc\">\n<div class=\"gb-element-8c2160fa\">\n<img loading=\"lazy\" decoding=\"async\" width=\"714\" height=\"192\" class=\"gb-media-0dd4b46b\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/rep-fr-1.webp\" title=\"rep-3x\" srcset=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/rep-fr-1.webp 819w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/rep-fr-1-300x67.webp 300w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/rep-fr-1-768x172.webp 768w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/rep-fr-1-18x4.webp 18w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/rep-fr-1-600x134.webp 600w\" sizes=\"auto, (max-width: 714px) 100vw, 714px\" \/>\n<\/div>\n\n\n\n<div class=\"gb-element-3070a71d\">\n<img loading=\"lazy\" decoding=\"async\" width=\"748\" height=\"192\" class=\"gb-media-1a2ce470\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/ada-fr.webp\" title=\"ada-cerp-3x\" srcset=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/ada-fr.webp 1257w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/ada-fr-300x66.webp 300w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/ada-fr-1024x225.webp 1024w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/ada-fr-768x169.webp 768w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/ada-fr-18x4.webp 18w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/ada-fr-600x132.webp 600w\" sizes=\"auto, (max-width: 748px) 100vw, 748px\" \/>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-ba3d3c65\">\n<div class=\"gb-element-ba322b28  grid-container\">\n<div class=\"gb-element-52a9119d\">\n<div class=\"gb-element-2a1cc70d\">\n<h2 class=\"gb-text gb-text-0b9afb0c\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-pt-dark-green-color\"><em>Renforcez vos comp\u00e9tences<\/em> <\/mark>avec une formation d'expert en Botox\u00ae et en esth\u00e9tique faciale<\/h2>\n\n\n\n<p class=\"gb-text gb-text-faca65b2\">Introduire Botox\u00ae dans votre cabinet dentaire ou m\u00e9dical peut \u00eatre un d\u00e9fi. Vous devez avoir confiance en vous et poss\u00e9der les comp\u00e9tences cliniques n\u00e9cessaires pour offrir aux patients les meilleurs soins possibles. Au PTIFAT, la formation bas\u00e9e sur l'anatomie et les preuves, la profondeur de l'enseignement clinique, les mod\u00e8les d'injection \u00e9prouv\u00e9s et les protocoles cliniques fournissent un tel niveau de comp\u00e9tence clinique et de ma\u00eetrise qu'il a \u00e9t\u00e9 adopt\u00e9 par divers organismes de r\u00e9glementation \u00e0 travers le Canada pour aider \u00e0 d\u00e9velopper l'approche \" Botox\u00ae \".<strong>canadiennes<\/strong>\"pour le Botox\u00ae et l'esth\u00e9tique du visage.<\/p>\n\n\n\n<p class=\"gb-text gb-text-1317e4de\">Mais l'anatomie profonde et la formation clinique approfondie ne constituent qu'une partie de la solution.<\/p>\n\n\n\n<ul class=\"wp-block-list wf-vertical-list-bulletp\">\n<li class=\"has-pt-text-color-color has-text-color has-link-color wp-elements-2a3fe3e7c0c791fe3a47d7465a73fdc1\"><strong>Int\u00e9gration de l'\u00e9quipe<\/strong> - Le d\u00e9veloppement d'une pratique r\u00e9ussie n\u00e9cessite une collaboration sans faille entre les membres de l'\u00e9quipe.<\/li>\n\n\n\n<li class=\"has-pt-text-color-color has-text-color has-link-color wp-elements-174eeca68639539181ca5ea3aed55b3e\"><strong>Soutien continu<\/strong> - Obtenez de l'aide et des conseils chaque fois que vous en avez besoin.<\/li>\n\n\n\n<li class=\"has-pt-text-color-color has-text-color has-link-color wp-elements-a9f5cdf0e1b968c80be132b1854b51b3\"><strong>Programme global<\/strong> - Con\u00e7ue pour \u00eatre digeste et pratique.<\/li>\n\n\n\n<li class=\"has-pt-text-color-color has-text-color has-link-color wp-elements-9dd785f3d93027b1e53df73dfd5b2c07\"><strong>Comp\u00e9tences n\u00e9cessaires<\/strong> - Acqu\u00e9rir toute l'expertise n\u00e9cessaire pour tirer parti de cette opportunit\u00e9.<\/li>\n\n\n\n<li class=\"has-pt-text-color-color has-text-color has-link-color wp-elements-a70f0c0df22a38245fa57cdca647ee98\"><strong>Des r\u00e9sultats pr\u00e9visibles et remarquables<\/strong> - Obtenir des r\u00e9sultats coh\u00e9rents et exceptionnels pour les patients.<\/li>\n\n\n\n<li class=\"has-pt-text-color-color has-text-color has-link-color wp-elements-478aa95d2901cf7747e3fd42d6472d03\"><strong>Croissance de la pratique<\/strong> - Mettez toutes les chances de votre c\u00f4t\u00e9 pour r\u00e9ussir dans le domaine du Botox et des injectables.<\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"gb-element-790f37bf\">\n<img loading=\"lazy\" decoding=\"async\" width=\"424\" height=\"462\" class=\"gb-media-14a42fb0\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/about-image.jpg\" title=\"\u00e0 propos de l&#039;image\" srcset=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/about-image.jpg 424w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/about-image-275x300.jpg 275w\" sizes=\"auto, (max-width: 424px) 100vw, 424px\" \/>\n\n\n\n<img loading=\"lazy\" decoding=\"async\" width=\"532\" height=\"375\" class=\"gb-media-ef85c5f3\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/Therapeutic-no-blood-cropped.webp\" title=\"Th\u00e9rapeutique-sans-sang-crois\u00e9\" alt=\"Femme recevant des injections de Botox dans son mass\u00e9ter pour des douleurs de type TMD.\" srcset=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/Therapeutic-no-blood-cropped.webp 532w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/Therapeutic-no-blood-cropped-300x211.webp 300w\" sizes=\"auto, (max-width: 532px) 100vw, 532px\" \/>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-5528964c\">\n<div class=\"gb-element-d55b60a2  grid-container\">\n<div class=\"gb-element-2d418269\">\n<div class=\"gb-element-cdee590b\">\n<img loading=\"lazy\" decoding=\"async\" width=\"547\" height=\"488\" class=\"gb-media-d8533ae6\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/dr-warren.jpg\" title=\"dr-warren\" srcset=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/dr-warren.jpg 547w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/dr-warren-300x268.jpg 300w\" sizes=\"auto, (max-width: 547px) 100vw, 547px\" \/>\n<\/div>\n\n\n\n<div class=\"gb-element-7bf36cf0\">\n<h2 class=\"gb-text gb-text-9d3cca13\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-pt-dark-green-color\"><em>Dr Warren Roberts :<\/em> <\/mark>Un leader dans le domaine du Botox<em>\u00ae<\/em> &amp; Injectables pour le visage<\/h2>\n\n\n\n<p class=\"gb-text gb-text-f891effd\"><span style=\"text-decoration: underline;\"><a href=\"\/fr\/a-propos-de\/dr-warren-roberts\/\">Dr. Warren Roberts<\/a>,<\/span> bas\u00e9 juste \u00e0 la p\u00e9riph\u00e9rie de Vancouver, en Colombie-Britannique, est actuellement \u00e0 la t\u00eate de l'industrie des produits injectables pour le visage. Depuis 2008, il a form\u00e9 plus de 8 000 praticiens \u00e0 l'\u00e9chelle internationale et a trait\u00e9 des centaines de patients au Botox.<em>\u00ae<\/em> patients. Gr\u00e2ce \u00e0 son engagement \u00e0 offrir l'excellence dans ce domaine, le contenu de son programme et son mod\u00e8le \u00e9ducatif sont maintenant adopt\u00e9s par divers organismes de r\u00e9glementation \u00e0 travers le Canada pour \u00e9tablir les \"normes de pratique\".<\/p>\n\n\n\n<p class=\"gb-text gb-text-a00e276d\">En outre, PTIFAT continue d'\u00e9tablir la norme pour les proc\u00e9dures de rajeunissement du visage gr\u00e2ce \u00e0 son d\u00e9veloppement pionnier du&nbsp;<span style=\"text-decoration: underline;\"><a href=\"https:\/\/ptifa.com\/fr\/p\/produits\/syllabus-de-photographie-clinique-ameliorer-votre-documentation-acceptation-des-cas\/\">S\u00e9rie de photographies sur le rajeunissement facial de Roberts<\/a><\/span>&nbsp;qui g\u00e9n\u00e8re un taux d'acceptation des cas de 99%, la&nbsp;<span style=\"text-decoration: underline;\"><a href=\"https:\/\/ptifa.com\/fr\/p\/cours\/niveau-2-botox-de-base-fr\/\">Mod\u00e8le de rep\u00e8re anatomique PTIFA<\/a><\/span>Le mod\u00e8le d'injection du PTIFAT (th\u00e9rapeutique et cosm\u00e9tique) et la technique d'injection du PTIFAT.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-fee4b02c\">\n<div class=\"gb-element-b57fc698  grid-container\">\n<div class=\"wp-block-group is-vertical is-content-justification-left is-nowrap is-layout-flex wp-container-core-group-is-layout-cfee1719 wp-block-group-is-layout-flex\">\n<div class=\"gb-element-fbe06b0c\">\n<h2 class=\"gb-text gb-text-2b577498\">Facult\u00e9 fondatrice<\/h2>\n\n\n\n<p class=\"gb-text gb-text-63054e84\">En 2008, les docteurs Roberts ont cofond\u00e9 PTIFAT et ont \u00e9t\u00e9 des leaders d'opinion et des formateurs cl\u00e9s dans le domaine de l'esth\u00e9tique et de la th\u00e9rapeutique faciales. Reconnus par Dentistry Today comme l'un des principaux leaders en mati\u00e8re de formation continue, ils ont \u00e9tabli la norme en mati\u00e8re de formation continue sur le Botox\u00ae et ont fourni un enseignement clinique d'une profondeur sans pr\u00e9c\u00e9dent. Reconnu pour le plus haut niveau de comp\u00e9tence clinique, d'efficacit\u00e9 et de pratiques de soins aux patients, le programme des Drs Roberts a \u00e9t\u00e9 <a href=\"https:\/\/ptifa.com\/fr\/accreditation\/\">adopt\u00e9 par plusieurs coll\u00e8ges de r\u00e9glementation au Canada<\/a> pour \u00e9tablir leur norme de pratique.<\/p>\n\n\n\n<div class=\"gb-element-4b0bc271\">\n<div class=\"gb-element-b05ca458\">\n<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"410\" class=\"gb-media-48d61828\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/warren-roberts.jpg\" title=\"dr-warren-roberts\" srcset=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/warren-roberts.jpg 400w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/warren-roberts-293x300.jpg 293w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\n\n\n\n<div class=\"gb-element-3102305d\">\n<h6 class=\"gb-text gb-text-543d74b4\">Dr. Warren Roberts<\/h6>\n\n\n\n<p class=\"gb-text gb-text-0f7e1770 small-text\">Co-fondateur et directeur clinique<\/p>\n\n\n\n<p class=\"gb-text gb-text-6b806063 small-link\"><a href=\"https:\/\/ptifa.com\/fr\/a-propos-de\/dr-warren-roberts\/\">Voir plus<\/a><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-70c1fdde\">\n<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"410\" class=\"gb-media-9c36d6d4\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/jan-roberts.jpg\" title=\"dr-jan-roberts\" srcset=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/jan-roberts.jpg 400w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/jan-roberts-293x300.jpg 293w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\n\n\n\n<div class=\"gb-element-3e36d7c7\">\n<h6 class=\"gb-text gb-text-b3967d98\"><strong>Dr. Jan Roberts<\/strong><\/h6>\n\n\n\n<p class=\"gb-text gb-text-0a87d35d small-text\">Co-fondateur et instructeur clinique principal<\/p>\n\n\n\n<p class=\"gb-text gb-text-70471a6f small-link\"><a href=\"https:\/\/ptifa.com\/fr\/a-propos-de\/dr-jan-robert\/\">Voir plus<\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"gb-text gb-text-2fec13da\">Soutien \u00e0 la facult\u00e9<\/h2>\n\n\n\n<p class=\"gb-text gb-text-e7a0e3f9\">Notre corps professoral est un groupe s\u00e9lectionn\u00e9 de professionnels canadiens tr\u00e8s talentueux, choisis pour leur niveau de comp\u00e9tence exceptionnel et leur d\u00e9vouement aux valeurs de PTIFAT, qui consiste \u00e0 fournir le plus haut niveau d'enseignement et de soins aux patients. La taille de notre corps professoral est r\u00e9duite afin de maintenir un enseignement clinique exceptionnel, d'assurer une exp\u00e9rience d'apprentissage coh\u00e9rente et de favoriser les liens personnels.<\/p>\n\n\n\n<div class=\"gb-element-c4dbc182\">\n<div class=\"gb-element-290a2df6\">\n<img decoding=\"async\" class=\"gb-media-fea838cb\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/phill-tzemis-1-1.jpg\" title=\"dr-warren-roberts\"\/>\n\n\n\n<div class=\"gb-element-04b8d60b\">\n<h6 class=\"gb-text gb-text-16933283\">Dr. Phill Tzemis<\/h6>\n\n\n\n<p class=\"gb-text gb-text-1eb70b5b small-text\">Dentiste<\/p>\n\n\n\n<p class=\"gb-text gb-text-8b30bafb small-link\"><a href=\"https:\/\/ptifa.com\/fr\/a-propos-de\/dr-phill-tzemis\/\">Voir plus<\/a><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-6b24bbc1\">\n<img decoding=\"async\" class=\"gb-media-4e21da7c\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/jared-nabeta-1-1.jpg\" title=\"dr-warren-roberts\"\/>\n\n\n\n<div class=\"gb-element-2342346d\">\n<h6 class=\"gb-text gb-text-8ed094f1\">Dr. Jared Nabeta<\/h6>\n\n\n\n<p class=\"gb-text gb-text-d7c6eda8 small-text\">Dentiste<\/p>\n\n\n\n<p class=\"gb-text gb-text-10661e93 small-link\"><a href=\"https:\/\/ptifa.com\/fr\/a-propos-de\/dr-jared-nabeta\/\">Voir plus<\/a><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-0828ca96\">\n<img loading=\"lazy\" decoding=\"async\" width=\"528\" height=\"540\" class=\"gb-media-c0f27c33\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/john-montague-1-1.jpg\" title=\"dr-warren-roberts\" srcset=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/john-montague-1-1.jpg 528w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/john-montague-1-1-293x300.jpg 293w\" sizes=\"auto, (max-width: 528px) 100vw, 528px\" \/>\n\n\n\n<div class=\"gb-element-4d740be2\">\n<h6 class=\"gb-text gb-text-114863ca\">Dr. John Montague<\/h6>\n\n\n\n<p class=\"gb-text gb-text-b01ec9bf small-text\">Dentiste<\/p>\n\n\n\n<p class=\"gb-text gb-text-92df60c6 small-link\"><a href=\"https:\/\/ptifa.com\/fr\/a-propos-de\/dr-john-montague\/\">Voir plus<\/a><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-0aa4198b\">\n<img loading=\"lazy\" decoding=\"async\" width=\"528\" height=\"540\" class=\"gb-media-27134911\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/kimit-rai-1-1.jpg\" title=\"dr-warren-roberts\" srcset=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/kimit-rai-1-1.jpg 528w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/kimit-rai-1-1-293x300.jpg 293w\" sizes=\"auto, (max-width: 528px) 100vw, 528px\" \/>\n\n\n\n<div class=\"gb-element-4761692d\">\n<h6 class=\"gb-text gb-text-eba53ce2\">Dr. Kimit Rai<\/h6>\n\n\n\n<p class=\"gb-text gb-text-2d5fdbba small-text\">Chirurgien plasticien<\/p>\n\n\n\n<p class=\"gb-text gb-text-e6e03e19 small-link\"><a href=\"https:\/\/ptifa.com\/fr\/a-propos-de\/dr-kimit-rai\/\">Voir plus<\/a><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-509f9a0f\">\n<img loading=\"lazy\" decoding=\"async\" width=\"528\" height=\"540\" class=\"gb-media-cdafd652\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/trevor-morhaliek-1-1.jpg\" title=\"dr-warren-roberts\" srcset=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/trevor-morhaliek-1-1.jpg 528w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/trevor-morhaliek-1-1-293x300.jpg 293w\" sizes=\"auto, (max-width: 528px) 100vw, 528px\" \/>\n\n\n\n<div class=\"gb-element-27110f4b\">\n<h6 class=\"gb-text gb-text-17ef3c8a\">Dr. Trevor Morhaliek<\/h6>\n\n\n\n<p class=\"gb-text gb-text-5a9d205f small-text\">Dentiste<\/p>\n\n\n\n<p class=\"gb-text gb-text-148f83e2 small-link\"><a href=\"https:\/\/ptifa.com\/fr\/a-propos-de\/dr-trevor-morhaliek\/\">Voir plus<\/a><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-b8cbe312\">\n<img loading=\"lazy\" decoding=\"async\" width=\"528\" height=\"540\" class=\"gb-media-3e2810e6\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/etaoin-quinn-1-1.jpg\" title=\"dr-warren-roberts\" srcset=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/etaoin-quinn-1-1.jpg 528w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/etaoin-quinn-1-1-293x300.jpg 293w\" sizes=\"auto, (max-width: 528px) 100vw, 528px\" \/>\n\n\n\n<div class=\"gb-element-b2e3230e\">\n<h6 class=\"gb-text gb-text-1b2d28b2\">Dr. Etaoin Quinn<\/h6>\n\n\n\n<p class=\"gb-text gb-text-155661f8 small-text\">Dentiste<\/p>\n\n\n\n<p class=\"gb-text gb-text-79e1193f small-link\"><a href=\"https:\/\/ptifa.com\/fr\/a-propos-de\/dr-etaoin-quinn\/\">Voir plus<\/a><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-e5ac23ff\">\n<img loading=\"lazy\" decoding=\"async\" width=\"528\" height=\"540\" class=\"gb-media-6067d915\" alt=\"\" title=\"ken-hamin\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/ken-hamin.webp\" srcset=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/ken-hamin.webp 528w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/ken-hamin-293x300.webp 293w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/ken-hamin-12x12.webp 12w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/ken-hamin-300x307.webp 300w\" sizes=\"auto, (max-width: 528px) 100vw, 528px\" \/>\n\n\n\n<div class=\"gb-element-9055079c\">\n<h6 class=\"gb-text gb-text-9c486278\">Dr. Ken Hamin<\/h6>\n\n\n\n<p class=\"gb-text gb-text-510c6b21 small-text\">Dentiste<\/p>\n\n\n\n<p class=\"gb-text gb-text-66b9f823 small-link\"><a href=\"https:\/\/ptifa.com\/fr\/a-propos-de\/dr-ken-hamin-2\/\">Voir plus<\/a><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-2a18d11a\">\n<img loading=\"lazy\" decoding=\"async\" width=\"528\" height=\"540\" class=\"gb-media-bebee49e\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/joshua-kirkpatrick.webp\" title=\"joshua-kirkpatrick\" alt=\"\" srcset=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/joshua-kirkpatrick.webp 528w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/joshua-kirkpatrick-293x300.webp 293w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/joshua-kirkpatrick-12x12.webp 12w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/joshua-kirkpatrick-300x307.webp 300w\" sizes=\"auto, (max-width: 528px) 100vw, 528px\" \/>\n\n\n\n<div class=\"gb-element-af829fc3\">\n<h6 class=\"gb-text gb-text-6f8be4b2\">Dr. Josh Kirkpatrick<\/h6>\n\n\n\n<p class=\"gb-text gb-text-41c0442c small-text\">Dentiste<\/p>\n\n\n\n<p class=\"gb-text gb-text-3fc33380 small-link\"><a href=\"https:\/\/ptifa.com\/fr\/a-propos-de\/dr-josh-kirkpatrick\/\">Voir plus<\/a><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-f85a137c\">\n<img loading=\"lazy\" decoding=\"async\" width=\"528\" height=\"540\" class=\"gb-media-64d3efc9\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/sarah-cloutier-toupin.webp\" title=\"sarah-cloutier-toupin\" alt=\"\" srcset=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/sarah-cloutier-toupin.webp 528w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/sarah-cloutier-toupin-293x300.webp 293w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/sarah-cloutier-toupin-12x12.webp 12w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/sarah-cloutier-toupin-300x307.webp 300w\" sizes=\"auto, (max-width: 528px) 100vw, 528px\" \/>\n\n\n\n<div class=\"gb-element-98da7eb7\">\n<h6 class=\"gb-text gb-text-fb7381a8\">Dr. Sarah Cloutier-Toupin<\/h6>\n\n\n\n<p class=\"gb-text gb-text-5fcccc48 small-text\">Dentiste<\/p>\n\n\n\n<p class=\"gb-text gb-text-fa60fc4d small-link\"><a href=\"https:\/\/ptifa.com\/fr\/a-propos-de\/dr-sarah-cloutier-toupin\/\">Voir plus<\/a><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-304fcbc2\">\n<img loading=\"lazy\" decoding=\"async\" width=\"528\" height=\"540\" class=\"gb-media-85a94121\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/etienne-giguere.webp\" title=\"etienne-giguere\" alt=\"\" srcset=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/etienne-giguere.webp 528w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/etienne-giguere-293x300.webp 293w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/etienne-giguere-12x12.webp 12w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/etienne-giguere-300x307.webp 300w\" sizes=\"auto, (max-width: 528px) 100vw, 528px\" \/>\n\n\n\n<div class=\"gb-element-8f606006\">\n<h6 class=\"gb-text gb-text-72198998\">Dr. Etienne Giguere<\/h6>\n\n\n\n<p class=\"gb-text gb-text-042cd115 small-text\">Dentiste<\/p>\n\n\n\n<p class=\"gb-text gb-text-ad4c524f small-link\"><a href=\"https:\/\/ptifa.com\/fr\/a-propos-de\/dr-etienne-giguere\/\">Voir plus<\/a><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-cb7fde3a\">\n<img loading=\"lazy\" decoding=\"async\" width=\"528\" height=\"540\" class=\"gb-media-519f6a64\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/jason-retter.webp\" title=\"jason-retter\" alt=\"\" srcset=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/jason-retter.webp 528w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/jason-retter-293x300.webp 293w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/jason-retter-12x12.webp 12w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/jason-retter-300x307.webp 300w\" sizes=\"auto, (max-width: 528px) 100vw, 528px\" \/>\n\n\n\n<div class=\"gb-element-feb9619d\">\n<h6 class=\"gb-text gb-text-909a140a\">Dr. Jason Retter<\/h6>\n\n\n\n<p class=\"gb-text gb-text-83b8076a small-text\">Dentiste<\/p>\n\n\n\n<p class=\"gb-text gb-text-5a502f04 small-link\"><a href=\"https:\/\/ptifa.com\/fr\/a-propos-de\/dr-jason-retter\/\">Voir plus<\/a><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-d26477bd\">\n<img loading=\"lazy\" decoding=\"async\" width=\"528\" height=\"540\" class=\"gb-media-fa02164d\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/melanie-vallee.webp\" title=\"m\u00e9lanie-vall\u00e9e\" alt=\"\" srcset=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/melanie-vallee.webp 528w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/melanie-vallee-293x300.webp 293w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/melanie-vallee-12x12.webp 12w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/melanie-vallee-300x307.webp 300w\" sizes=\"auto, (max-width: 528px) 100vw, 528px\" \/>\n\n\n\n<div class=\"gb-element-4c9444d8\">\n<h6 class=\"gb-text gb-text-58f99bc7\">Dr. M\u00e9lanie Vall\u00e9e<\/h6>\n\n\n\n<p class=\"gb-text gb-text-272730e6 small-text\">Dentiste<\/p>\n\n\n\n<p class=\"gb-text gb-text-b6ea0359 small-link\"><a href=\"https:\/\/ptifa.com\/fr\/a-propos-de\/dr-melanie-vallee\/\">Voir plus<\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-f904e308\">\n<div class=\"gb-element-a7727332  grid-container\">\n<div class=\"wp-block-group is-vertical is-content-justification-left is-nowrap is-layout-flex wp-container-core-group-is-layout-cfee1719 wp-block-group-is-layout-flex\">\n<div class=\"gb-element-969e6d66\">\n<div class=\"gb-element-3059635e\">\n<img loading=\"lazy\" decoding=\"async\" width=\"52\" height=\"37\" class=\"gb-media-d466978e\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/media-icon.svg\" title=\"ic\u00f4ne-m\u00e9dia\"\/>\n\n\n\n<h2 class=\"gb-text gb-text-294bf37a\">Nous sommes dans les m\u00e9dias<\/h2>\n\n\n\n<p class=\"gb-text gb-text-c4c8a924\">D\u00e9couvrez certains de nos articles publi\u00e9s dans des revues et publications dentaires de premier plan, qui mettent en valeur l'expertise et l'innovation du Dr Roberts en mati\u00e8re de Botox dans la dentisterie.<\/p>\n<\/div>\n\n\n\n<div class=\"gb-query-a3d62a07\"><div class=\"gb-looper-4daee2e6\">\n<div class=\"gb-loop-item gb-loop-item-967ca5b0 post-1969 research-and-article type-research-and-article status-publish has-post-thumbnail hentry\">\n<div class=\"gb-element-6f3944b9\">\n\n\n<div class=\"gb-element-0b190d38\">\n\n\n<h4 class=\"gb-text gb-text-7d8d59e5\">Inside Dentistry<\/h4>\n\n\n\n<p class=\"gb-text gb-text-3c898257 small-text\">Rajeunissement du visage dans le cadre de la conception du sourire\n\n<\/p>\n\n\n<\/div>\n<\/div>\n<\/div>\n\n<div class=\"gb-loop-item gb-loop-item-967ca5b0 post-1976 research-and-article type-research-and-article status-publish has-post-thumbnail hentry\">\n<div class=\"gb-element-6f3944b9\">\n\n\n<div class=\"gb-element-0b190d38\">\n\n\n<h4 class=\"gb-text gb-text-7d8d59e5\">Optimiste Delta<\/h4>\n\n\n\n<p class=\"gb-text gb-text-3c898257 small-text\">Roberts Dental propose des services \u00e9largis<\/p>\n\n\n<\/div>\n<\/div>\n<\/div>\n\n<div class=\"gb-loop-item gb-loop-item-967ca5b0 post-1979 research-and-article type-research-and-article status-publish has-post-thumbnail hentry\">\n<div class=\"gb-element-6f3944b9\">\n\n\n<div class=\"gb-element-0b190d38\">\n\n\n<h4 class=\"gb-text gb-text-7d8d59e5\">Spectrum Dental Travail d'\u00e9quipe<\/h4>\n\n\n\n<p class=\"gb-text gb-text-3c898257 small-text\">Utilisation th\u00e9rapeutique de la toxine botulique pour le traitement des maladies parodontales<\/p>\n\n\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<a class=\"gb-text gb-text-d4f9210c wf-button-regular-dark\" href=\"https:\/\/ptifa.com\/fr\/articles-de-recherche\/\">Voir tous les articles de recherche<\/a>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-e301741b\">\n<div class=\"gb-element-68893f29\">\n<div class=\"gb-element-5f6f512d  grid-container\">\n<img loading=\"lazy\" decoding=\"async\" width=\"44\" height=\"94\" class=\"gb-media-b593cbd5\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/section-icon.svg\" title=\"ic\u00f4ne de section\"\/>\n\n\n\n<div class=\"wp-block-group is-vertical is-content-justification-left is-nowrap is-layout-flex wp-container-core-group-is-layout-cfee1719 wp-block-group-is-layout-flex\">\n<div class=\"gb-element-5cac5850\">\n<div class=\"gb-element-7f8e3b1b\">\n<h2 class=\"gb-text gb-text-578605ac\">La formation PTIFAT <em><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-pt-secondary-color\">Avantage<\/mark><\/em><\/h2>\n<\/div>\n\n\n\n<div class=\"gb-element-05e3e285\">\n<div class=\"gb-element-e2234a41\">\n<div class=\"gb-element-94bdb805\">\n<div class=\"gb-element-d2b7056a\">\n<div class=\"gb-element-deb9ea55\"><\/div>\n\n\n\n<div class=\"gb-element-99e60443\">\n<img loading=\"lazy\" decoding=\"async\" width=\"102\" height=\"34\" class=\"gb-media-58721104\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/Group-25.svg\" title=\"Groupe 25\"\/>\n<\/div>\n\n\n\n<div class=\"gb-element-d7cdd0d8\">\n<h6 class=\"gb-text gb-text-0873b051\">Cours typique de Botox<\/h6>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-41aefcbd\">\n<div class=\"gb-element-e0658308\">\n<p class=\"gb-text gb-text-c78682f5\">Heures d'anatomie&nbsp;<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-e60713c5\">\n<p class=\"gb-text gb-text-a9025b0d\">(+ de 16 h)<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-d947be07\">\n<p class=\"gb-text gb-text-d7a4d80b\">1-2 heures<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-aa8a578c\">\n<div class=\"gb-element-3d2bf819\">\n<p class=\"gb-text gb-text-0c728745\">Heures d'exp\u00e9rience pratique&nbsp;<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-bcd3a531\">\n<p class=\"gb-text gb-text-1278e58f\">(+ de 16 h)<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-da3b1a65\">\n<p class=\"gb-text gb-text-c2753bed\">4 heures<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-590e285f\">\n<div class=\"gb-element-c18b8a59\">\n<p class=\"gb-text gb-text-40366e41\">Nombre d'injections sur mod\u00e8le de patient<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-e843d660\">\n<p class=\"gb-text gb-text-0060fe8e\">8+<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-f05fdf8a\">\n<p class=\"gb-text gb-text-13645099\">Rarement<\/p>\n<\/div>\n<\/div>\n\n\n\n<div>\n<div class=\"gb-element-46990fed\">\n<div class=\"gb-element-39275563\">\n<p class=\"gb-text gb-text-9b98d111\">Cr\u00e9dits de formation<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-80467dea\">\n<p class=\"gb-text gb-text-23c22b59\">+ de 58 CE\/CM&nbsp;<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-10dd033d\">\n<p class=\"gb-text gb-text-4e5e7d3f\">4-8 CE\/CME<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-c8c7eed3\">\n<div class=\"gb-element-80400f32\">\n<p class=\"gb-text gb-text-08b6651e\">Formation \u00e0 la photographie<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-c3daaad9\">\n<img loading=\"lazy\" decoding=\"async\" width=\"25\" height=\"25\" class=\"gb-media-8df1a3e6\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/star-mark.svg\" title=\"marque-\u00e9toile\"\/>\n<\/div>\n\n\n\n<div class=\"gb-element-142c543f\">\n<p class=\"gb-text gb-text-f409e771\">Limit\u00e9e<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-1d35a24e\">\n<div class=\"gb-element-3b724ce5\">\n<p class=\"gb-text gb-text-48ef048a\"><strong>Applications enseign\u00e9es\u00a0: \u00e0 la fois th\u00e9rapeutiques<\/strong> et esth\u00e9tiques<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-1b9de5b3\">\n<img loading=\"lazy\" decoding=\"async\" width=\"25\" height=\"25\" class=\"gb-media-65fe5881\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/star-mark.svg\" title=\"marque-\u00e9toile\"\/>\n<\/div>\n\n\n\n<div class=\"gb-element-cbc9faba\">\n<img loading=\"lazy\" decoding=\"async\" width=\"25\" height=\"25\" class=\"gb-media-85b3e92e\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/minus-icon.svg\" title=\"ic\u00f4ne moins\"\/>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-06899d12\">\n<div class=\"gb-element-c11bb8cb\">\n<p class=\"gb-text gb-text-8c87b091\">Pratique de l'int\u00e9gration enseign\u00e9e<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-8ff98d10\">\n<img loading=\"lazy\" decoding=\"async\" width=\"25\" height=\"25\" class=\"gb-media-bbff89e8\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/star-mark.svg\" title=\"marque-\u00e9toile\"\/>\n<\/div>\n\n\n\n<div class=\"gb-element-9231b4b4\">\n<img loading=\"lazy\" decoding=\"async\" width=\"25\" height=\"25\" class=\"gb-media-bb2d6a2c\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/minus-icon.svg\" title=\"ic\u00f4ne moins\"\/>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-72ec4325\">\n<div class=\"gb-element-9c14e6c6\">\n<p class=\"gb-text gb-text-5ecb29a1\">Soutien au marketing<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-3d69f1dc\">\n<img loading=\"lazy\" decoding=\"async\" width=\"25\" height=\"25\" class=\"gb-media-656d0f91\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/star-mark.svg\" title=\"marque-\u00e9toile\"\/>\n<\/div>\n\n\n\n<div class=\"gb-element-c0024757\">\n<img loading=\"lazy\" decoding=\"async\" width=\"25\" height=\"25\" class=\"gb-media-623ae031\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/minus-icon.svg\" title=\"ic\u00f4ne moins\"\/>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-4edbad6a\">\n<div class=\"gb-element-61fcb135\">\n<p class=\"gb-text gb-text-f124e1df\">Soutien \u00e0 la pratique du suivi<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-f4b3d4f5\">\n<img loading=\"lazy\" decoding=\"async\" width=\"25\" height=\"25\" class=\"gb-media-c4916068\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/star-mark.svg\" title=\"marque-\u00e9toile\"\/>\n<\/div>\n\n\n\n<div class=\"gb-element-211dc5c8\">\n<img loading=\"lazy\" decoding=\"async\" width=\"25\" height=\"25\" class=\"gb-media-a9014a09\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/minus-icon.svg\" title=\"ic\u00f4ne moins\"\/>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-a4a3215c\">\n<div class=\"gb-element-db145e64\">\n<p class=\"gb-text gb-text-befe621f\">Exp\u00e9rience des enseignants<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-f9ddf640\">\n<img loading=\"lazy\" decoding=\"async\" width=\"25\" height=\"25\" class=\"gb-media-99a1006e\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/star-mark.svg\" title=\"marque-\u00e9toile\"\/>\n<\/div>\n\n\n\n<div class=\"gb-element-3d67b950\">\n<img loading=\"lazy\" decoding=\"async\" width=\"25\" height=\"25\" class=\"gb-media-7842aa38\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/minus-icon.svg\" title=\"ic\u00f4ne moins\"\/>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-b76c11f6\">\n<img loading=\"lazy\" decoding=\"async\" width=\"50\" height=\"71\" class=\"gb-media-12250ea2\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/cert.svg\" title=\"certitude\"\/>\n\n\n\n<div class=\"gb-element-9e6a7872\">\n<h5 class=\"gb-text gb-text-906b2b52\">Nombre <em><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-pt-secondary-color\">canadiennes<\/mark><\/em> de pratique des th\u00e9rapies esth\u00e9tiques du visage<\/h5>\n\n\n\n<p class=\"gb-text gb-text-9ec28ab8\">Notre formation et nos protocoles cliniques ont \u00e9tabli la norme au Canada pour le Botox.<em>\u00ae<\/em> et d\u00e9passent toutes les exigences de l'universit\u00e9.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-faa3dbf7\">\n<div class=\"gb-element-d0b6622a\">\n<img loading=\"lazy\" decoding=\"async\" width=\"37\" height=\"36\" class=\"gb-media-095ac129\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/skull-icon.svg\" title=\"ic\u00f4ne de t\u00eate de mort\"\/>\n\n\n\n<p class=\"gb-text gb-text-8d576fdd\">Bas\u00e9 sur l'anatomie<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-a3c254c0\">\n<img loading=\"lazy\" decoding=\"async\" width=\"37\" height=\"36\" class=\"gb-media-9f433759\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/experience.svg\" title=\"exp\u00e9rience\"\/>\n\n\n\n<p class=\"gb-text gb-text-7fa70506\">Travaux pratiques cliniques intensifs<br>sur l'exp\u00e9rience<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-6ea51c7a\">\n<img loading=\"lazy\" decoding=\"async\" width=\"37\" height=\"36\" class=\"gb-media-e24085b6\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/team-training.svg\" title=\"formation des \u00e9quipes\"\/>\n\n\n\n<p class=\"gb-text gb-text-5262d6a8\">Int\u00e9gration des pratiques &amp; <br>Formation de l'\u00e9quipe<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-047d3c03\">\n<img loading=\"lazy\" decoding=\"async\" width=\"37\" height=\"36\" class=\"gb-media-69618c0c\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/photography.svg\" title=\"photographie\"\/>\n\n\n\n<p class=\"gb-text gb-text-26921b54\">Formation \u00e0 la photographie<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>About Us Since 2008 PTIFAT has been leading the industry with anatomy-based Botox\u00ae training for dental, medical &amp; nursing professionals. About PTIFAT Video: Learn what makes PTIFAT a leader in the field of Botox Your browser does not support the video tag. Graduates years leading the industry hours anatomy-basedtraining Boost Your Skills with Expert Botox\u00ae &#8230; <a title=\"\u00c0 propos\" class=\"read-more\" href=\"https:\/\/ptifa.com\/fr\/about\/\" aria-label=\"Read more about About Us\">En savoir plus<\/a><\/p>","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-221","page","type-page","status-publish"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>About Us | Pacific Training Institute for Facial Aesthetics &amp; Therapeutics<\/title>\n<meta name=\"description\" content=\"Since 2008 PTIFAT has been leading the industry with anatomy-based Botox training for dental, medical &amp; nursing professionals.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ptifa.com\/fr\/a-propos-de\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"About Us | Pacific Training Institute for Facial Aesthetics &amp; Therapeutics\" \/>\n<meta property=\"og:description\" content=\"Since 2008 PTIFAT has been leading the industry with anatomy-based Botox training for dental, medical &amp; nursing professionals.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ptifa.com\/fr\/a-propos-de\/\" \/>\n<meta property=\"og:site_name\" content=\"Pacific Training Institute for Facial Aesthetics &amp; Therapeutics\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-03T19:35:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/section-icon.svg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ptifa.com\\\/about\\\/\",\"url\":\"https:\\\/\\\/ptifa.com\\\/about\\\/\",\"name\":\"About Us | Pacific Training Institute for Facial Aesthetics & Therapeutics\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ptifa.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ptifa.com\\\/about\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ptifa.com\\\/about\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ptifa.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/section-icon.svg\",\"datePublished\":\"2025-02-16T14:14:36+00:00\",\"dateModified\":\"2025-11-03T19:35:22+00:00\",\"description\":\"Since 2008 PTIFAT has been leading the industry with anatomy-based Botox training for dental, medical & nursing professionals.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ptifa.com\\\/about\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ptifa.com\\\/about\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/ptifa.com\\\/about\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ptifa.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/section-icon.svg\",\"contentUrl\":\"https:\\\/\\\/ptifa.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/section-icon.svg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ptifa.com\\\/about\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ptifa.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"About Us\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ptifa.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ptifa.com\\\/fr\\\/\",\"name\":\"Pacific Training Institute for Facial Aesthetics &amp; Therapeutics\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/ptifa.com\\\/fr\\\/#organization\"},\"alternateName\":\"PTIFAT\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ptifa.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ptifa.com\\\/fr\\\/#organization\",\"name\":\"Pacific Training Institute for Facial Aesthetics & Therapeutics\",\"alternateName\":\"PTIFAT\",\"url\":\"https:\\\/\\\/ptifa.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/ptifa.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ptifa.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/ptifa-logo.svg\",\"contentUrl\":\"https:\\\/\\\/ptifa.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/ptifa-logo.svg\",\"width\":310,\"height\":42,\"caption\":\"Pacific Training Institute for Facial Aesthetics & Therapeutics\"},\"image\":{\"@id\":\"https:\\\/\\\/ptifa.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A propos de nous - Pacific Training Institute for Facial Aesthetics &amp; Therapeutics","description":"Depuis 2008, PTIFAT est \u00e0 la pointe de l'industrie en mati\u00e8re de formation au Botox bas\u00e9e sur l'anatomie pour les professionnels des soins dentaires, m\u00e9dicaux et infirmiers.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ptifa.com\/fr\/a-propos-de\/","og_locale":"fr_CA","og_type":"article","og_title":"About Us | Pacific Training Institute for Facial Aesthetics & Therapeutics","og_description":"Since 2008 PTIFAT has been leading the industry with anatomy-based Botox training for dental, medical & nursing professionals.","og_url":"https:\/\/ptifa.com\/fr\/a-propos-de\/","og_site_name":"Pacific Training Institute for Facial Aesthetics &amp; Therapeutics","article_modified_time":"2025-11-03T19:35:22+00:00","og_image":[{"url":"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/section-icon.svg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Estimation du temps de lecture":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ptifa.com\/about\/","url":"https:\/\/ptifa.com\/about\/","name":"A propos de nous - Pacific Training Institute for Facial Aesthetics &amp; Therapeutics","isPartOf":{"@id":"https:\/\/ptifa.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ptifa.com\/about\/#primaryimage"},"image":{"@id":"https:\/\/ptifa.com\/about\/#primaryimage"},"thumbnailUrl":"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/section-icon.svg","datePublished":"2025-02-16T14:14:36+00:00","dateModified":"2025-11-03T19:35:22+00:00","description":"Depuis 2008, PTIFAT est \u00e0 la pointe de l'industrie en mati\u00e8re de formation au Botox bas\u00e9e sur l'anatomie pour les professionnels des soins dentaires, m\u00e9dicaux et infirmiers.","breadcrumb":{"@id":"https:\/\/ptifa.com\/about\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ptifa.com\/about\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/ptifa.com\/about\/#primaryimage","url":"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/section-icon.svg","contentUrl":"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/section-icon.svg"},{"@type":"BreadcrumbList","@id":"https:\/\/ptifa.com\/about\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ptifa.com\/"},{"@type":"ListItem","position":2,"name":"About Us"}]},{"@type":"WebSite","@id":"https:\/\/ptifa.com\/fr\/#website","url":"https:\/\/ptifa.com\/fr\/","name":"Institut de formation du Pacifique pour l'esth\u00e9tique faciale et la th\u00e9rapeutique","description":"","publisher":{"@id":"https:\/\/ptifa.com\/fr\/#organization"},"alternateName":"PTIFAT","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ptifa.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/ptifa.com\/fr\/#organization","name":"Institut de formation du Pacifique pour l'esth\u00e9tique faciale et la th\u00e9rapeutique","alternateName":"PTIFAT","url":"https:\/\/ptifa.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/ptifa.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/ptifa-logo.svg","contentUrl":"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/ptifa-logo.svg","width":310,"height":42,"caption":"Pacific Training Institute for Facial Aesthetics & Therapeutics"},"image":{"@id":"https:\/\/ptifa.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/ptifa.com\/fr\/wp-json\/wp\/v2\/pages\/221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ptifa.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ptifa.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ptifa.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ptifa.com\/fr\/wp-json\/wp\/v2\/comments?post=221"}],"version-history":[{"count":131,"href":"https:\/\/ptifa.com\/fr\/wp-json\/wp\/v2\/pages\/221\/revisions"}],"predecessor-version":[{"id":5800,"href":"https:\/\/ptifa.com\/fr\/wp-json\/wp\/v2\/pages\/221\/revisions\/5800"}],"wp:attachment":[{"href":"https:\/\/ptifa.com\/fr\/wp-json\/wp\/v2\/media?parent=221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}