{"id":3037,"date":"2025-03-30T00:13:15","date_gmt":"2025-03-30T00:13:15","guid":{"rendered":"https:\/\/ptifa.com\/?post_type=product&#038;p=3037"},"modified":"2026-04-08T16:41:48","modified_gmt":"2026-04-08T16:41:48","slug":"formation-dequipe-de-niveau-4","status":"publish","type":"product","link":"https:\/\/ptifa.com\/fr\/p\/courses\/level-4-team-training\/","title":{"rendered":"Dermal Filler Team Fundamentals"},"content":{"rendered":"<div>\n<h2 class=\"gb-text gb-text-e33c0b94\">Ce que vous apprendrez<\/h2>\n\n\n\n<p class=\"gb-text gb-text-66279411\"><img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"12\" class=\"wp-image-944\" style=\"width: 16px\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/bullet-point.svg\" alt=\"\"> Apprendre&nbsp;<strong>Les protocoles \u00e9prouv\u00e9s de PTIFAT&nbsp;<\/strong>pour introduire avec succ\u00e8s les produits de comblement dermique dans tout type de cabinet dentaire ou m\u00e9dical.<br><img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"12\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/bullet-point.svg\" alt=\"\">&nbsp;Apprendre&nbsp;<strong>communiquer les avantages du traitement de comblement dermique<\/strong>&nbsp;et g\u00e9rer les attentes des patients avec confiance et professionnalisme.<br><img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"12\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/bullet-point.svg\" alt=\"\">&nbsp;Recevoir une formation pratique sur&nbsp;<strong>m\u00e9lange\/dilution de seringues, canules, photographie clinique, facturation<\/strong>&nbsp;&amp; plus.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"gb-text gb-text-d3457885\">Rencontre avec le directeur clinique<\/h2>\n\n\n\n<div class=\"gb-element-b05ca458\">\n<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"205\" class=\"gb-media-48d61828\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/dr-warren-roberts-.jpg\" title=\"dr-warren-roberts-\"\/>\n\n\n\n<div class=\"gb-element-3102305d\">\n<h4 class=\"gb-text gb-text-543d74b4\">Dr. Warren Roberts<\/h4>\n\n\n\n<p class=\"gb-text gb-text-0f7e1770\">Cofondateur et directeur clinique<\/p>\n\n\n\n<div>\n<p class=\"gb-text gb-text-12fe76e1 small-text\">Le Dr Warren Roberts est le cofondateur et le directeur clinique du Pacific Training Institute for Facial Aesthetics and Therapeutics. Il est professeur clinicien \u00e0 la retraite au d\u00e9partement des sciences de la sant\u00e9 bucco-dentaire de l'universit\u00e9 de Colombie-Britannique.&nbsp;<\/p>\n\n\n\n<p class=\"gb-text gb-text-bda9298c see-more-content small-text\" id=\"meet-your-instructor\">Le Dr Warren Roberts est le cofondateur et le directeur clinique du Pacific Training Institute for Facial Aesthetics and Therapeutics. Il est professeur clinicien \u00e0 la retraite au d\u00e9partement des sciences de la sant\u00e9 bucco-dentaire de l'universit\u00e9 de Colombie-Britannique. <\/p>\n\n\n\n<p class=\"gb-text gb-text-47e6f43a small-text see-more inline\" data-pointer=\"meet-your-instructor\"> <span style=\"text-decoration: underline\">Plus d'informations<\/span> <span style=\"text-decoration: underline\"><img loading=\"lazy\" decoding=\"async\" width=\"10\" height=\"6\" class=\"wp-image-2748\" style=\"width: 10px\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/arrow-down.svg\" alt=\"\"><\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"gb-text gb-text-39e14c6a\">D\u00e9tails du cours<\/h2>\n\n\n\n<p>Elevate your expertise to elite status with our comprehensive Dermal Filler Team Fundamentals course\u2014the ultimate preparation for supporting sophisticated aesthetic procedures. This intensive program transforms experienced clinical support staff into invaluable procedural partners through immersive online learning and hands-on practice.<\/p>\n\n\n\n<p>La formation didactique en ligne fournit des connaissances th\u00e9oriques essentielles et des protocoles pour les proc\u00e9dures complexes, en se concentrant sur les applications avanc\u00e9es de comblement dermique et les techniques sp\u00e9cialis\u00e9es. La formation pratique clinique vous place directement dans un environnement clinique, offrant une exp\u00e9rience pratique supervis\u00e9e pour aider les praticiens \u00e0 traiter des patients en direct.<\/p>\n\n\n\n<p>Ma\u00eetriser des comp\u00e9tences avanc\u00e9es, notamment<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Techniques de photographie sp\u00e9cialis\u00e9es pour une documentation pr\u00e9cise sur l'obturation<\/li>\n\n\n\n<li>Pr\u00e9paration avanc\u00e9e des seringues pour les r\u00e9gions anatomiques complexes, y compris les m\u00e9langes et les dilutions<\/li>\n\n\n\n<li>Protocoles pr\u00e9 et post-traitement pour des r\u00e9sultats optimaux pour le patient<\/li>\n\n\n\n<li>Reconnaissance des complications et soutien pendant les protocoles d'urgence<\/li>\n<\/ul>\n\n\n\n<p>Upon completion, you&#8217;ll receive official certification documenting your advanced qualifications, positioning you as an essential team member for sophisticated aesthetic procedures. Through your practitioner, gain exclusive access to our Support Study Club community for ongoing education and case support.<\/p>\n\n\n\n<p>Votre parcours professionnel atteindra son plus haut niveau : la confiance en soi et la comp\u00e9tence dans les proc\u00e9dures esth\u00e9tiques les plus exigeantes !<\/p>\n\n\n\n<div class=\"gb-element-073743c6 dashed-left\">\n<p class=\"gb-text gb-text-9186d6b9\"><\/p>\n\n\n\n<h3 class=\"gb-text gb-text-41a83470\">Section didactique en ligne<\/h3>\n\n\n\n<p class=\"gb-text gb-text-e0909388 small-text\"><\/p>\n\n\n\n<div class=\"gb-element-bfc4c2ee\">\n<div class=\"gb-accordion gb-accordion-c1a60147\">\n<div class=\"gb-accordion__item gb-accordion__item-366b72ba gb-accordion__item-open\">\n<div role=\"button\" tabindex=\"0\" class=\"gb-accordion__toggle gb-accordion__toggle-325e1560 gb-block-is-current\" id=\"gb-accordion-toggle-325e1560\">\n<span class=\"gb-text gb-text-a21f0f95\">Vid\u00e9os des cours<\/span>\n\n\n\n<span class=\"gb-accordion__toggle-icon gb-accordion__toggle-icon-b75dc948\"><span class=\"gb-accordion__toggle-icon-open\"><\/span><span class=\"gb-accordion__toggle-icon-close\"><\/span><\/span>\n<\/div>\n\n\n\n<div class=\"gb-accordion__content\" id=\"gb-accordion-content-76b5dc1d\">\n<div class=\"gb-element-f769f743\">\n<div class=\"gb-element-cbf35337\">\n<div class=\"gb-element-6459e12a\">\n<p class=\"gb-text gb-text-9284bc81\">1.1 &#8211; Introduction to Dermal Fillers<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-86f888b3\">\n<div class=\"gb-element-7df5ad0d\">\n<p class=\"gb-text gb-text-25947862\"><\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-e408fc2c\">\n<p class=\"gb-text gb-text-45dc70ae\">22 min<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-1f5ac074\">\n<div class=\"gb-element-fc2a2249\">\n<p class=\"gb-text gb-text-1e877876\">1.2. &#8211; Records<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-cdce39eb\">\n<div class=\"gb-element-8ff47d2b\">\n<p class=\"gb-text gb-text-a4d72edf\"><\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-6704201b\">\n<p class=\"gb-text gb-text-6630cce1\">38 min<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-0d105622\">\n<div class=\"gb-element-f7efbeb5\">\n<p class=\"gb-text gb-text-61d61583\">1.3 &amp; 1.4 &#8211; Office Requirements &amp; Tray Set-up<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-c0e7190a\">\n<div class=\"gb-element-df6cea5d\">\n<p class=\"gb-text gb-text-69dd5590\"><\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-b790b05e\">\n<p class=\"gb-text gb-text-3be0fde8\">39 min<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-b9106c09\">\n<div class=\"gb-element-961be84d\">\n<p class=\"gb-text gb-text-93bda7f4\">1.5 &#8211; Billing<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-a222e34d\">\n<div class=\"gb-element-4eb45253\">\n<p class=\"gb-text gb-text-65805f76\"><\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-23d5573c\">\n<p class=\"gb-text gb-text-40a32e98\">30 minutes<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-d8b43230\">\n<div class=\"gb-element-527f9166\">\n<p class=\"gb-text gb-text-4b3b454a\">1.5 &#8211; Recare<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-188ae31d\">\n<div class=\"gb-element-a22c7923\">\n<p class=\"gb-text gb-text-df36e7e0\"><\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-399974e1\">\n<p class=\"gb-text gb-text-b51500c5\">38 min<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-6c518c8e\">\n<div class=\"gb-element-376ebe6d\">\n<p class=\"gb-text gb-text-c4813305\">1.6 &#8211; Filler Connector for Blending\/Diluting<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-af15efd1\">\n<div class=\"gb-element-220dfd56\">\n<p class=\"gb-text gb-text-abbb5d80\"><\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-e2dde780\">\n<p class=\"gb-text gb-text-0264de6d\">17 min<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-0502ef58\">\n<div class=\"gb-element-217801d1\">\n<p class=\"gb-text gb-text-f8730fd4\">1.7 &#8211; Easy Guide Cannula Guidance<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-23e28160\">\n<div class=\"gb-element-ecc5f7bd\">\n<p class=\"gb-text gb-text-54725279\"><\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-d87c95b0\">\n<p class=\"gb-text gb-text-8cf106ed\">12 min<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-accordion__item gb-accordion__item-f203a618\">\n<div role=\"button\" tabindex=\"0\" class=\"gb-accordion__toggle gb-accordion__toggle-03140901\" id=\"gb-accordion-toggle-03140901\">\n<span class=\"gb-text gb-text-0ff0a3d1\">Examen<\/span>\n<\/div>\n\n\n\n<div class=\"gb-accordion__content\" id=\"gb-accordion-content-34552a11\"><\/div>\n<\/div>\n\n\n\n<div class=\"gb-accordion__item gb-accordion__item-8e5d2ce6\">\n<div role=\"button\" tabindex=\"0\" class=\"gb-accordion__toggle gb-accordion__toggle-2b862030\" id=\"gb-accordion-toggle-2b862030\">\n<span class=\"gb-text gb-text-188af2dc\">Formulaires et ressources m\u00e9dicales<\/span>\n\n\n\n<span class=\"gb-accordion__toggle-icon gb-accordion__toggle-icon-5a74acd2\"><span class=\"gb-accordion__toggle-icon-open\"><\/span><span class=\"gb-accordion__toggle-icon-close\"><\/span><\/span>\n<\/div>\n\n\n\n<div class=\"gb-accordion__content\" id=\"gb-accordion-content-91367e0d\">\n<div class=\"gb-element-7d666b32\">\n<div class=\"gb-element-4c820541\">\n<div class=\"gb-element-bfad1756\">\n<p class=\"gb-text gb-text-430c9228\">Consentement au traitement de comblement dermique (mod\u00e8les modifiables)<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-71b0c352\">\n<div class=\"gb-element-99810e8e\">\n<p class=\"gb-text gb-text-6990d783\"><\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-a6ea6ebb\">\n<p class=\"gb-text gb-text-a988d1df\"><\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-4a6cccc4\">\n<div class=\"gb-element-e3ffe93a\">\n<p class=\"gb-text gb-text-9e19de4d\">Instructions postop\u00e9ratoires pour les produits de comblement dermique<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-79429fb8\">\n<div class=\"gb-element-00c9fdf7\">\n<p class=\"gb-text gb-text-a429b09b\"><\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-19153e8c\">\n<p class=\"gb-text gb-text-9b8f2441\"><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<h3 class=\"gb-text gb-text-a35c5bc5\">Session clinique pratique<\/h3>\n\n\n\n<div class=\"gb-element-d8898d4a\">\n<img loading=\"lazy\" decoding=\"async\" width=\"23\" height=\"23\" class=\"gb-media-9db52439 image-fit-height\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/clinical.svg\" title=\"clinique\"\/>\n\n\n\n<div>\n<h5 class=\"gb-text gb-text-8cb9bdc9\">Plongez dans une exp\u00e9rience clinique intensive qui transforme votre capacit\u00e9 \u00e0 prendre en charge les traitements de comblement dermique :<\/h5>\n\n\n\n<p><br>Plongez dans le monde r\u00e9el en travaillant avec des praticiens qui administrent des traitements de comblement dermique \u00e0 des patients mod\u00e8les. Cette journ\u00e9e clinique intensive transforme vos connaissances th\u00e9oriques en expertise pratique gr\u00e2ce \u00e0 une exp\u00e9rience guid\u00e9e et pratique des proc\u00e9dures r\u00e9elles.<\/p>\n\n\n\n<p>Graduate with comprehensive skills that make you instrumental in successfully integrating dermal filler services into your medical or dental practice. Upon successful completion, you&#8217;ll receive official certification and a complete suite of implementation-ready forms. Your journey continues with exclusive access to our online Support Study Club through your practitioner\u2014connecting you with ongoing case support, continuing education resources, and a community of aesthetic professionals.<\/p>\n\n\n\n<a class=\"gb-text-f470a832 small-text see-more\" data-pointer=\"day-1\"><span class=\"gb-text\">Afficher la journ\u00e9e compl\u00e8te<\/span><span class=\"gb-shape\">\n\n\n<\/span><\/a>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"gb-text gb-text-43f2f47e\">Ce cours est id\u00e9al pour<\/h2>\n\n\n\n<p>This course is geared for non-injecting team members, including: Dental Assistants (DA&#8217;s), Office Managers, Receptionists, Hygienists (RDH&#8217;s), Medical Office Assistants (MOA&#8217;s) &amp; other support staff.<\/p>\n\n\n\n<h2 class=\"gb-text gb-text-56f54e79\">Frais et exigences<\/h2>\n\n\n\n<div>\n<div class=\"gb-element-d41520ad\">\n<div class=\"gb-element-522f1a0e\">\n<p class=\"gb-text gb-text-a86611b6\">Frais de scolarit\u00e9 pour les membres de l'\u00e9quipe :&nbsp;<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-a9590e3f\">\n<p class=\"gb-text\"><strong>$999<\/strong>&nbsp;CAD (plus TPS)<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-a85ec567\">\n<div class=\"gb-element-f171b6f6\">\n<p class=\"gb-text gb-text-d8e23b64\">Pr\u00e9-requis :<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-6d3a8cf8\">\n<p class=\"gb-text\">Ce cours s'adresse \u00e0 tous, quels que soient les ant\u00e9c\u00e9dents ou l'exp\u00e9rience ant\u00e9rieure. Aucun pr\u00e9requis ou qualification n'est n\u00e9cessaire - il suffit d'apporter son enthousiasme et sa volont\u00e9 d'apprendre. <\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-8267191e\">\n<img loading=\"lazy\" decoding=\"async\" width=\"227\" height=\"155\" class=\"gb-media-6babbbf3\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/chart-fr.svg\" title=\"tableau\"\/>\n\n\n\n<div>\n<h2 class=\"gb-text gb-text-0d7560a7\">30%*<\/h2>\n\n\n\n<h4 class=\"gb-text gb-text-63d173bd\">croissance des recettes<\/h4>\n\n\n\n<p class=\"gb-text gb-text-a3c7dcb3 small-text\">* Les praticiens form\u00e9s par PTIFAT voient leurs revenus annuels augmenter de 30% au cours de la premi\u00e8re ann\u00e9e.<\/p>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"gb-text gb-text-8961e368\">FAQ du cours<\/h2>\n\n\n\n<div class=\"gb-accordion gb-accordion-e13a3377\">\n<div class=\"gb-accordion__item gb-accordion__item-03cc4db3\">\n<div role=\"button\" tabindex=\"0\" class=\"gb-accordion__toggle gb-accordion__toggle-dec3ecaa\" id=\"gb-accordion-toggle-dec3ecaa\">\n<span class=\"gb-text gb-text-469ab87b\">Pendant combien de temps aurai-je acc\u00e8s au mat\u00e9riel en ligne ?<\/span>\n\n\n\n<span class=\"gb-accordion__toggle-icon gb-accordion__toggle-icon-09d9537b\"><span class=\"gb-accordion__toggle-icon-open\"><\/span><span class=\"gb-accordion__toggle-icon-close\"><\/span><\/span>\n<\/div>\n\n\n\n<div class=\"gb-accordion__content\" id=\"gb-accordion-content-732ab659\">\n<div class=\"gb-element-eceab857\">\n<p>L'acc\u00e8s au mat\u00e9riel de cours en ligne est accord\u00e9 pour une dur\u00e9e d'un an.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-accordion__item gb-accordion__item-2259b751\">\n<div role=\"button\" tabindex=\"0\" class=\"gb-accordion__toggle gb-accordion__toggle-adf6c0d6\" id=\"gb-accordion-toggle-adf6c0d6\">\n<span class=\"gb-text gb-text-89230ad9\">Recevrai-je des cr\u00e9dits CE\/CME ?<\/span>\n\n\n\n<span class=\"gb-accordion__toggle-icon gb-accordion__toggle-icon-6b8d7191\"><span class=\"gb-accordion__toggle-icon-open\"><\/span><span class=\"gb-accordion__toggle-icon-close\"><\/span><\/span>\n<\/div>\n\n\n\n<div class=\"gb-accordion__content\" id=\"gb-accordion-content-c2a3f650\">\n<div class=\"gb-element-315c5fa6\">\n<p>Oui, nous sommes un prestataire de formation agr\u00e9\u00e9 par l'ADA CERP et un certificat d'ach\u00e8vement sera fourni \u00e0 la fin du cours.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"gb-text gb-text-cfdcea2d\">Vous avez encore une question ?<\/h2>\n\n\n\n<div class=\"gb-element-770c675a\">\n<div class=\"gb-element-f38c39cc\">\n<img loading=\"lazy\" decoding=\"async\" width=\"56\" height=\"56\" class=\"gb-media-b87dbeb7\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/phone-1.svg\" title=\"t\u00e9l\u00e9phone-1\"\/>\n\n\n\n<div>\n<h6 class=\"gb-text gb-text-848b6a13\">Nous contacter<\/h6>\n\n\n\n<p class=\"gb-text gb-text-79181dbf small-link\"><a href=\"https:\/\/ptifa.com\/fr\/nous-contacter\/\">Envoyer un message<\/a><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-eed5f3f9\">\n<img loading=\"lazy\" decoding=\"async\" width=\"56\" height=\"56\" class=\"gb-media-b645dc7b\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/phone-2.svg\" title=\"t\u00e9l\u00e9phone-2\"\/>\n\n\n\n<div>\n<h6 class=\"gb-text gb-text-ba2b8604\">Appelez-nous<\/h6>\n\n\n\n<p class=\"gb-text gb-text-a85f42dd small-link\"><a href=\"tel:18556810066\">1-855-681-0066<\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"gb-text gb-text-03c9e80b\">Reconnaissance et accr\u00e9ditation CE\/CME<\/h2>\n\n\n\n<p class=\"gb-text\">PTIFAT est un prestataire reconnu par l'ADA CERP. L'ADA CERP est un service de l'American Dental Association qui aide les professionnels dentaires \u00e0 identifier les prestataires de qualit\u00e9 en mati\u00e8re de formation dentaire continue.<\/p>\n\n\n\n<p class=\"gb-text gb-text-8bf4fe34\">ADA CERP does not approve or endorse individual courses or instructors, nor does it imply acceptance of credit hours by boards of dentistry. PTIFAT designates Dermal Filler Team Fundamentals course for 12 hours of continuing education credits.<\/p>\n\n\n\n<div class=\"gb-element-40564722\">\n<div class=\"gb-element-c17da12f\">\n<img loading=\"lazy\" decoding=\"async\" width=\"499\" height=\"128\" class=\"gb-media-607e272b\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/ada-fr.webp\" title=\"ada-cerp-banner\" srcset=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/ada-fr.webp 1257w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/ada-fr-300x66.webp 300w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/ada-fr-1024x225.webp 1024w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/ada-fr-768x169.webp 768w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/ada-fr-18x4.webp 18w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/ada-fr-600x132.webp 600w\" sizes=\"auto, (max-width: 499px) 100vw, 499px\" \/>\n<\/div>\n\n\n\n<div class=\"gb-element-827479a9\">\n<img loading=\"lazy\" decoding=\"async\" width=\"476\" height=\"128\" class=\"gb-media-bbfb96be\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/rep-fr-1.webp\" title=\"reconnu-\u00e9ducatif\" srcset=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/rep-fr-1.webp 819w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/rep-fr-1-300x67.webp 300w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/rep-fr-1-768x172.webp 768w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/rep-fr-1-18x4.webp 18w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/rep-fr-1-600x134.webp 600w\" sizes=\"auto, (max-width: 476px) 100vw, 476px\" \/>\n<\/div>\n\n\n\n<div class=\"gb-element-6d9b1ae6\">\n<img loading=\"lazy\" decoding=\"async\" width=\"844\" height=\"528\" class=\"gb-media-1a278e5a\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/aogd-q.webp\" title=\"aogd-q\" srcset=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/aogd-q.webp 844w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/aogd-q-300x188.webp 300w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/aogd-q-768x480.webp 768w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/aogd-q-600x375.webp 600w\" sizes=\"auto, (max-width: 844px) 100vw, 844px\" \/>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"gb-text gb-text-5a5d8e23\">Les r\u00e9ussites de nos dipl\u00f4m\u00e9s<\/h2>\n\n\n\n<div class=\"gb-element-fe5fcd64\">\n<div class=\"gb-element-2d4ac503\">\n<h5 class=\"gb-text gb-text-4d9e92c8\">\"J'ai suivi ce cours il y a de nombreuses ann\u00e9es, et \u00e0 nouveau le week-end dernier. Il \u00e9tait fantastique dans le pass\u00e9, et le contenu n'a fait qu'\u00e9voluer et s'am\u00e9liorer. J'ai une grande exp\u00e9rience de l'injection, mais j'ai tout de m\u00eame acquis de nouvelles connaissances utiles et b\u00e9n\u00e9fiques. Pour un praticien d\u00e9butant les injections, comme pour quelqu'un qui le fait depuis des ann\u00e9es, ce cours est la r\u00e9f\u00e9rence en Am\u00e9rique du Nord et je le recommande vivement.<\/h5>\n\n\n\n<div class=\"gb-element-38c51242\">\n<div class=\"gb-element-0cc862da\">\n<img loading=\"lazy\" decoding=\"async\" width=\"90\" height=\"122\" class=\"gb-media-fa42a26b\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/Dr.VishalSharma2.jpg\" title=\"Dr. VishalSharma2\" alt=\"Dr. Vishal Sharma\"\/>\n\n\n\n<div>\n<h6 class=\"gb-text gb-text-6ae005bf\">Dr. Vishal Sharma (Dentiste)<\/h6>\n\n\n\n<p class=\"gb-text gb-text-ac68e961\">Calgary, AB<\/p>\n<\/div>\n<\/div>\n\n\n\n<a href=\"#\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"112\" height=\"116\" class=\"gb-media-7d54a387 image-auto-height-content\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/Google-Reviews-Icon.webp\" title=\"Ic\u00f4ne Google-Reviews\" alt=\"Avis de Google.\"\/><\/a>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-373aea02\">\n<h5 class=\"gb-text gb-text-8f9178e7\">\"Le cours du Dr Roberts est tr\u00e8s syst\u00e9matique et complet. Je me sens pr\u00eate \u00e0 commencer \u00e0 administrer le Botox dans mon cabinet imm\u00e9diatement apr\u00e8s le cours. Les ressources en ligne facilitent la pr\u00e9paration et l'\u00e9tude du cours \u00e0 l'avance.\"<\/h5>\n\n\n\n<div class=\"gb-element-7e73d2a9\">\n<div class=\"gb-element-fc56ceae\">\n<img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" class=\"gb-media-48dc047a\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/neda-refati.png\" title=\"neda-refati\" alt=\"Dr. Neda Refati\" srcset=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/neda-refati.png 120w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/neda-refati-100x100.png 100w\" sizes=\"auto, (max-width: 120px) 100vw, 120px\" \/>\n\n\n\n<div>\n<h6 class=\"gb-text gb-text-13267f8c\">Dr. Neda Refati (Dentiste)<\/h6>\n\n\n\n<p class=\"gb-text gb-text-8613c665\">Vancouver, BC<\/p>\n<\/div>\n<\/div>\n\n\n\n<a href=\"#\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"112\" height=\"116\" class=\"gb-media-86e5dc35 image-auto-height-content\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/Google-Reviews-Icon.webp\" title=\"Ic\u00f4ne Google-Reviews\" alt=\"Avis de Google.\"\/><\/a>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-d9c322e0\">\n<h5 class=\"gb-text gb-text-91d4cac9\">\"Le meilleur cours que j'ai suivi depuis l'obtention de mon dipl\u00f4me en 1996.<\/h5>\n\n\n\n<div class=\"gb-element-a7cbaa86\">\n<div class=\"gb-element-7539d331\">\n<img loading=\"lazy\" decoding=\"async\" width=\"78\" height=\"82\" class=\"gb-media-0661da41\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/Marianne-Stelmaschuk.jpg\" title=\"Marianne-Stelmaschuk\" alt=\"Dr. Marianne Stelmaschuk\"\/>\n\n\n\n<div>\n<h6 class=\"gb-text gb-text-cb905ba6\">Dr. Marianne Stelmaschuk (Dentiste)<\/h6>\n\n\n\n<div>\n<p class=\"gb-text gb-text-f938357a\">Lloydminster, AB<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<a href=\"#\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"20\" height=\"20\" class=\"gb-media-e64d9e36 image-auto-height-content\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/facebook-brands-solid-1.svg\" title=\"facebook-marques-solidaires 1\"\/><\/a>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-b600a684\">\n<h5 class=\"gb-text gb-text-6b6a5f90\">\"Une formation continue extr\u00eamement bien organis\u00e9e. L'un des meilleurs cours pratiques jamais organis\u00e9s !\"<\/h5>\n\n\n\n<div class=\"gb-element-b63d7166\">\n<div class=\"gb-element-baa901ec\">\n<img loading=\"lazy\" decoding=\"async\" width=\"116\" height=\"122\" class=\"gb-media-608c3fd4\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/Kenneth-Banks.jpg\" title=\"Kenneth-Banks\" alt=\"Dr. Kenneth Banks\"\/>\n\n\n\n<div>\n<h6 class=\"gb-text gb-text-09dce00e\">Dr. Kenneth Banks (Dentiste)<\/h6>\n\n\n\n<p class=\"gb-text gb-text-285ccd43\">Inwood, WV<\/p>\n<\/div>\n<\/div>\n\n\n\n<a href=\"#\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"20\" height=\"20\" class=\"gb-media-3e445bf7 image-auto-height-content\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/facebook-brands-solid-1.svg\" title=\"facebook-marques-solidaires 1\"\/><\/a>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-b2058832\">\n<h5 class=\"gb-text gb-text-facdcfc1\">\"Une excellente journ\u00e9e d'apprentissage aujourd'hui. L'attention port\u00e9e \u00e0 l'anatomie\/aux marquages et \u00e0 la technique d'injection est sup\u00e9rieure \u00e0 beaucoup d'autres cours. Merci !\"<\/h5>\n\n\n\n<div class=\"gb-element-89516ab4\">\n<div class=\"gb-element-14456e5f\">\n<img loading=\"lazy\" decoding=\"async\" width=\"108\" height=\"122\" class=\"gb-media-1252bd6d\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/Tracey-Ruddick.jpg\" title=\"Tracey-Ruddick\" alt=\"Dr. Tracey Ruddick\"\/>\n\n\n\n<div>\n<h6 class=\"gb-text gb-text-804d3da5\">Dr. Tracey Ruddick (Dentiste)<\/h6>\n\n\n\n<p class=\"gb-text gb-text-bdfec96b\">Canmore, AB<\/p>\n<\/div>\n<\/div>\n\n\n\n<a href=\"#\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"20\" height=\"20\" class=\"gb-media-1bbfa175 image-auto-height-content\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/facebook-brands-solid-1.svg\" title=\"facebook-marques-solidaires 1\"\/><\/a>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-a8238e59\">\n<h5 class=\"gb-text gb-text-8f05d2a0\">\"L'un des meilleurs cours sur le Botox. Je recommande vivement le cours du Dr Roberts, si vous envisagez une carri\u00e8re r\u00e9ussie dans les injections de Botox. Lui et le Dr. Jan sont pleins de connaissances et ils sont d\u00e9sireux de partager leur richesse de savoir.\"<\/h5>\n\n\n\n<div class=\"gb-element-9915537f\">\n<div class=\"gb-element-3a9b21e2\">\n<img loading=\"lazy\" decoding=\"async\" width=\"108\" height=\"116\" class=\"gb-media-0b6feb45\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/Roocha-Vyas.jpg\" title=\"Roocha-Vyas\" alt=\"Dr. Roocha Vyas\"\/>\n\n\n\n<div>\n<h6 class=\"gb-text gb-text-a5a66d73\">Dr. Roocha Vyas (Dentiste)<\/h6>\n\n\n\n<p class=\"gb-text gb-text-1c1f5839\">Thornhill, ON<\/p>\n<\/div>\n<\/div>\n\n\n\n<a href=\"#\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"20\" height=\"20\" class=\"gb-media-1a628128 image-auto-height-content\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/facebook-brands-solid-1.svg\" title=\"facebook-marques-solidaires 1\"\/><\/a>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-ac9a7b05  grid-container\">\n<div class=\"wp-block-group is-vertical is-content-justification-left is-nowrap is-layout-flex wp-container-core-group-is-layout-cfee1719 wp-block-group-is-layout-flex\">\n<div class=\"gb-element-8da68eaa\">\n<div class=\"gb-element-68a6ece7\">\n<h2 class=\"gb-text gb-text-05ef0eef\">La formation PTIFAT <em><mark class=\"has-inline-color has-pt-secondary-color\">Avantage<\/mark><\/em><\/h2>\n<\/div>\n\n\n\n<div class=\"gb-element-6166b982\">\n<div class=\"gb-element-1623a727\">\n<div class=\"gb-element-71ba05d1\">\n<div class=\"gb-element-760da07c\">\n<div class=\"gb-element-75c71084\"><\/div>\n\n\n\n<div class=\"gb-element-35bc22b8\">\n<img loading=\"lazy\" decoding=\"async\" width=\"102\" height=\"34\" class=\"gb-media-16188991\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/Group-25.svg\" title=\"Groupe 25\"\/>\n<\/div>\n\n\n\n<div class=\"gb-element-31062c47\">\n<h6 class=\"gb-text gb-text-b8671a26\">Cours typique de Botox<\/h6>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-729d6bb3\">\n<div class=\"gb-element-c4fb4479\">\n<p class=\"gb-text gb-text-feb8df71\">Heures d'anatomie&nbsp;<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-682ade11\">\n<p class=\"gb-text gb-text-87212dbe\">(+ de 16 h)<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-52d047cb\">\n<p class=\"gb-text gb-text-ef3d770e\">1-2 heures<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-2d795284\">\n<div class=\"gb-element-d114f51d\">\n<p class=\"gb-text gb-text-c1bf3a2f\">Heures d'exp\u00e9rience pratique&nbsp;<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-89baa251\">\n<p class=\"gb-text gb-text-5b0d4512\">(+ de 16 h)<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-c87df779\">\n<p class=\"gb-text gb-text-403e34d3\">4 heures<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-eb101f82\">\n<div class=\"gb-element-c94bde30\">\n<p class=\"gb-text gb-text-9ed20de3\">Nombre d'injections sur mod\u00e8le de patient<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-0f42d711\">\n<p class=\"gb-text gb-text-31005933\">8+<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-87e61b34\">\n<p class=\"gb-text gb-text-21c82092\">Rarement<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-ba20e79c\">\n<div class=\"gb-element-d40e1f12\">\n<p class=\"gb-text gb-text-4db07750\">Formation \u00e0 la photographie<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-48b6a8f6\">\n<img loading=\"lazy\" decoding=\"async\" width=\"25\" height=\"25\" class=\"gb-media-cdaad92a\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/star-mark.svg\" title=\"marque-\u00e9toile\"\/>\n<\/div>\n\n\n\n<div class=\"gb-element-f07c5fe1\">\n<p class=\"gb-text gb-text-00500a26\">Limit\u00e9e<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-5ffc8429\">\n<div class=\"gb-element-0fa1f45b\">\n<p class=\"gb-text gb-text-aab9d936\"><strong>Applications enseign\u00e9es\u00a0: \u00e0 la fois th\u00e9rapeutiques<\/strong> et esth\u00e9tiques<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-803d6eb5\">\n<img loading=\"lazy\" decoding=\"async\" width=\"25\" height=\"25\" class=\"gb-media-556b0ff5\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/star-mark.svg\" title=\"marque-\u00e9toile\"\/>\n<\/div>\n\n\n\n<div class=\"gb-element-ac603857\">\n<img loading=\"lazy\" decoding=\"async\" width=\"25\" height=\"25\" class=\"gb-media-a6864046\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/minus-icon.svg\" title=\"ic\u00f4ne moins\"\/>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-8258c17e\">\n<div class=\"gb-element-79218a3a\">\n<p class=\"gb-text gb-text-4e8233ef\">Pratique de l'int\u00e9gration enseign\u00e9e<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-f5302b96\">\n<img loading=\"lazy\" decoding=\"async\" width=\"25\" height=\"25\" class=\"gb-media-eed17832\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/star-mark.svg\" title=\"marque-\u00e9toile\"\/>\n<\/div>\n\n\n\n<div class=\"gb-element-bf82ecd0\">\n<img loading=\"lazy\" decoding=\"async\" width=\"25\" height=\"25\" class=\"gb-media-863ce4bd\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/minus-icon.svg\" title=\"ic\u00f4ne moins\"\/>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-32716784\">\n<div class=\"gb-element-cd469734\">\n<p class=\"gb-text gb-text-ef72d45c\">Soutien au marketing<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-3e9eb108\">\n<img loading=\"lazy\" decoding=\"async\" width=\"25\" height=\"25\" class=\"gb-media-75c17ed7\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/star-mark.svg\" title=\"marque-\u00e9toile\"\/>\n<\/div>\n\n\n\n<div class=\"gb-element-26b03ce7\">\n<img loading=\"lazy\" decoding=\"async\" width=\"25\" height=\"25\" class=\"gb-media-2daad243\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/minus-icon.svg\" title=\"ic\u00f4ne moins\"\/>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-12800333\">\n<div class=\"gb-element-1cf34618\">\n<p class=\"gb-text gb-text-320cffb3\">Soutien \u00e0 la pratique du suivi<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-e188aad8\">\n<img loading=\"lazy\" decoding=\"async\" width=\"25\" height=\"25\" class=\"gb-media-6cc0dc12\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/star-mark.svg\" title=\"marque-\u00e9toile\"\/>\n<\/div>\n\n\n\n<div class=\"gb-element-ba0888da\">\n<img loading=\"lazy\" decoding=\"async\" width=\"25\" height=\"25\" class=\"gb-media-e6f83fc4\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/minus-icon.svg\" title=\"ic\u00f4ne moins\"\/>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-74622f4f\">\n<div class=\"gb-element-6abcb2f1\">\n<p class=\"gb-text gb-text-a70bb054\">Exp\u00e9rience des enseignants<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-aff36257\">\n<img loading=\"lazy\" decoding=\"async\" width=\"25\" height=\"25\" class=\"gb-media-3bfc889a\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/star-mark.svg\" title=\"marque-\u00e9toile\"\/>\n<\/div>\n\n\n\n<div class=\"gb-element-4d153b11\">\n<img loading=\"lazy\" decoding=\"async\" width=\"25\" height=\"25\" class=\"gb-media-d995a7b3\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/minus-icon.svg\" title=\"ic\u00f4ne moins\"\/>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-000e9c2a\">\n<img loading=\"lazy\" decoding=\"async\" width=\"50\" height=\"71\" class=\"gb-media-bd50bbbb\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/cert.svg\" title=\"certitude\"\/>\n\n\n\n<div class=\"gb-element-ffbb0170\">\n<h5 class=\"gb-text gb-text-2b509cd6\">Nombre <em><mark class=\"has-inline-color has-pt-secondary-color\">canadiennes<\/mark><\/em> de pratique des th\u00e9rapies esth\u00e9tiques du visage<\/h5>\n\n\n\n<p class=\"gb-text gb-text-e51ef975\">Notre formation et nos protocoles cliniques ont \u00e9tabli la norme au Canada et d\u00e9passent toutes les exigences de l'universit\u00e9.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<img loading=\"lazy\" decoding=\"async\" width=\"44\" height=\"94\" class=\"gb-media-a1d168cd\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/section-icon.svg\" title=\"ic\u00f4ne de section\"\/>\n<\/div>\n\n\n\n<h2 class=\"gb-text gb-text-37ab99b5\">Objectifs du cours<\/h2>\n\n\n\n<ol class=\"wp-block-list\">\n<li>D\u00e9crire comment les produits de comblement dermique peuvent \u00eatre utilis\u00e9s pour am\u00e9liorer les soins aux patients et les diff\u00e9rentes techniques d'injection.<\/li>\n\n\n\n<li>D\u00e9crire comment la toxine botulique peut \u00eatre utilis\u00e9e en conjonction avec un traitement de comblement dermique dans la partie moyenne et inf\u00e9rieure du visage.<\/li>\n\n\n\n<li>D\u00e9crire les protocoles de consultation avant le traitement, le consentement au traitement et les complications, les instructions postop\u00e9ratoires et les soins compl\u00e9mentaires apr\u00e8s deux semaines.<\/li>\n<\/ol>\n\n\n\n<h2 class=\"gb-text gb-text-397fef76\">Politique d'enregistrement<\/h2>\n\n\n\n<p>Nous nous engageons \u00e0 vous offrir une exp\u00e9rience \u00e9ducative et clinique sans pr\u00e9c\u00e9dent. Chaque cours a un nombre limit\u00e9 de places et comprend un ratio instructeur\/\u00e9tudiant \u00e9lev\u00e9. Pour y parvenir, nous consacrons une part importante de nos ressources et nous nous engageons aupr\u00e8s des membres de la facult\u00e9, des instructeurs, du personnel clinique, des patients, des lieux, des h\u00f4tels, etc. afin de nous assurer que le cours d\u00e9passe vos attentes.<\/p>\n\n\n\n<p><strong>L'inscription \u00e0 un cours est donc consid\u00e9r\u00e9e comme un engagement ferme de votre part.<\/strong><\/p>\n\n\n\n<p>Nous avons \u00e9tabli la politique d'enregistrement suivante :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Tous les paiements sont non remboursables et non transf\u00e9rables.<\/strong>y compris les cours en ligne et les commandes de produits.<\/li>\n\n\n\n<li>Il incombe \u00e0 chaque participant au cours de d\u00e9terminer si les traitements (toxine botulique, produits de comblement cutan\u00e9, etc.) rel\u00e8vent de son champ d'application en v\u00e9rifiant aupr\u00e8s de l'organisme de r\u00e9glementation de sa province. Nos cours d\u00e9passent g\u00e9n\u00e9ralement les exigences \u00e9ducatives fix\u00e9es par les organismes de r\u00e9glementation, mais il incombe aux participants de d\u00e9terminer et de respecter les restrictions et\/ou exigences de l'organisme directeur de leur province ou de leur \u00c9tat.<\/li>\n<\/ul>\n\n\n\n<div class=\"gb-element-69663f72\" id=\"full-policy\">\n<ul class=\"wp-block-list\">\n<li>L'acc\u00e8s au mat\u00e9riel de cours en ligne est accord\u00e9 pour une dur\u00e9e d'un an \u00e0 compter de l'inscription.<\/li>\n\n\n\n<li>Les changements de date pour tous les cours pratiques (y compris : Niveau 1B, Niveau 2, Niveau 3 et Niveau 4, Niveau 5, Niveau 6, Cours de remise \u00e0 niveau, Microneedling) ne sont pas autoris\u00e9s dans les 30 jours pr\u00e9c\u00e9dant les dates du cours. Tous les fonds seront perdus si le cours n'est pas suivi. Les changements effectu\u00e9s moins de 30 jours avant la date du cours sont soumis \u00e0 des frais de reprogrammation de $500.<\/li>\n\n\n\n<li>Les arrhes ne sont pas transf\u00e9rables et servent \u00e0 r\u00e9server une place pour une date de cours sp\u00e9cifique. Un acompte sera pr\u00e9lev\u00e9 au moment de l'inscription, le solde \u00e9tant d\u00fb 30 jours avant la date du cours.<\/li>\n\n\n\n<li>La PTIFA se r\u00e9serve le droit d'annuler, de reporter ou de modifier tout cours si n\u00e9cessaire.<\/li>\n\n\n\n<li>Le PTIFA n'est pas responsable des frais d'h\u00f4tel, des billets d'avion ou d'autres d\u00e9penses encourues en raison d'un changement ou d'une annulation de cours.<\/li>\n<\/ul>\n<\/div>\n\n\n\n<p class=\"gb-text small-link see-more\" data-pointer=\"full-policy\"><a href=\"#\">Voir la politique compl\u00e8te  <img loading=\"lazy\" decoding=\"async\" width=\"10\" height=\"6\" class=\"wp-image-1040\" style=\"width: 10px\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/Group-120.svg\" alt=\"\"><\/a><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Elevate your expertise to elite status with our comprehensive Dermal Filler Team Fundamentals course\u2014the ultimate preparation for supporting sophisticated aesthetic procedures.<\/p>","protected":false},"featured_media":3007,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[75,94],"product_tag":[],"class_list":{"0":"post-3037","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-courses","7":"product_cat-team-courses","8":"","9":"woocommerce-text-align-center","10":"woocommerce-image-align-center","12":"first","13":"outofstock","14":"taxable","15":"shipping-taxable","16":"purchasable","17":"product-type-variable"},"exclude_global_add_ons":[],"addons":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Advanced Dermal Filler Training for Dental &amp; Medical Teams<\/title>\n<meta name=\"description\" content=\"The training provides you with supervised hands-on experience supporting practitioners in sophisticated aesthetic procedures with live patient treatments .\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ptifa.com\/fr\/p\/cours\/formation-dequipe-de-niveau-4\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Advanced Dermal Filler Training for Dental &amp; Medical Teams\" \/>\n<meta property=\"og:description\" content=\"The training provides you with supervised hands-on experience supporting practitioners in sophisticated aesthetic procedures with live patient treatments .\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ptifa.com\/fr\/p\/cours\/formation-dequipe-de-niveau-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Pacific Training Institute for Facial Aesthetics &amp; Therapeutics\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-08T16:41:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/Dermal-Filler.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1613\" \/>\n\t<meta property=\"og:image:height\" content=\"1148\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data1\" content=\"14 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ptifa.com\\\/p\\\/courses\\\/level-4-team-training\\\/\",\"url\":\"https:\\\/\\\/ptifa.com\\\/p\\\/courses\\\/level-4-team-training\\\/\",\"name\":\"Advanced Dermal Filler Training for Dental & Medical Teams\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ptifa.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ptifa.com\\\/p\\\/courses\\\/level-4-team-training\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ptifa.com\\\/p\\\/courses\\\/level-4-team-training\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ptifa.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Dermal-Filler.webp\",\"datePublished\":\"2025-03-30T00:13:15+00:00\",\"dateModified\":\"2026-04-08T16:41:48+00:00\",\"description\":\"The training provides you with supervised hands-on experience supporting practitioners in sophisticated aesthetic procedures with live patient treatments .\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ptifa.com\\\/p\\\/courses\\\/level-4-team-training\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ptifa.com\\\/p\\\/courses\\\/level-4-team-training\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/ptifa.com\\\/p\\\/courses\\\/level-4-team-training\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ptifa.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Dermal-Filler.webp\",\"contentUrl\":\"https:\\\/\\\/ptifa.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Dermal-Filler.webp\",\"width\":1613,\"height\":1148,\"caption\":\"Women receiving dermal filler injection in her upper lip.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ptifa.com\\\/p\\\/courses\\\/level-4-team-training\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ptifa.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/ptifa.com\\\/fr\\\/produits\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dermal Filler Team Fundamentals\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ptifa.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ptifa.com\\\/fr\\\/\",\"name\":\"Pacific Training Institute for Facial Aesthetics &amp; Therapeutics\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/ptifa.com\\\/fr\\\/#organization\"},\"alternateName\":\"PTIFAT\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ptifa.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ptifa.com\\\/fr\\\/#organization\",\"name\":\"Pacific Training Institute for Facial Aesthetics & Therapeutics\",\"alternateName\":\"PTIFAT\",\"url\":\"https:\\\/\\\/ptifa.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/ptifa.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ptifa.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/ptifa-logo.svg\",\"contentUrl\":\"https:\\\/\\\/ptifa.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/ptifa-logo.svg\",\"width\":310,\"height\":42,\"caption\":\"Pacific Training Institute for Facial Aesthetics & Therapeutics\"},\"image\":{\"@id\":\"https:\\\/\\\/ptifa.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Formation avanc\u00e9e sur les produits de comblement dermique pour les \u00e9quipes dentaires et m\u00e9dicales","description":"La formation vous permet d'acqu\u00e9rir une exp\u00e9rience pratique supervis\u00e9e en aidant les praticiens \u00e0 r\u00e9aliser des proc\u00e9dures esth\u00e9tiques sophistiqu\u00e9es sur des patients en chair et en os.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ptifa.com\/fr\/p\/cours\/formation-dequipe-de-niveau-4\/","og_locale":"fr_CA","og_type":"article","og_title":"Advanced Dermal Filler Training for Dental & Medical Teams","og_description":"The training provides you with supervised hands-on experience supporting practitioners in sophisticated aesthetic procedures with live patient treatments .","og_url":"https:\/\/ptifa.com\/fr\/p\/cours\/formation-dequipe-de-niveau-4\/","og_site_name":"Pacific Training Institute for Facial Aesthetics &amp; Therapeutics","article_modified_time":"2026-04-08T16:41:48+00:00","og_image":[{"width":1613,"height":1148,"url":"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/Dermal-Filler.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimation du temps de lecture":"14 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ptifa.com\/p\/courses\/level-4-team-training\/","url":"https:\/\/ptifa.com\/p\/courses\/level-4-team-training\/","name":"Formation avanc\u00e9e sur les produits de comblement dermique pour les \u00e9quipes dentaires et m\u00e9dicales","isPartOf":{"@id":"https:\/\/ptifa.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ptifa.com\/p\/courses\/level-4-team-training\/#primaryimage"},"image":{"@id":"https:\/\/ptifa.com\/p\/courses\/level-4-team-training\/#primaryimage"},"thumbnailUrl":"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/Dermal-Filler.webp","datePublished":"2025-03-30T00:13:15+00:00","dateModified":"2026-04-08T16:41:48+00:00","description":"La formation vous permet d'acqu\u00e9rir une exp\u00e9rience pratique supervis\u00e9e en aidant les praticiens \u00e0 r\u00e9aliser des proc\u00e9dures esth\u00e9tiques sophistiqu\u00e9es sur des patients en chair et en os.","breadcrumb":{"@id":"https:\/\/ptifa.com\/p\/courses\/level-4-team-training\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ptifa.com\/p\/courses\/level-4-team-training\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/ptifa.com\/p\/courses\/level-4-team-training\/#primaryimage","url":"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/Dermal-Filler.webp","contentUrl":"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/Dermal-Filler.webp","width":1613,"height":1148,"caption":"Women receiving dermal filler injection in her upper lip."},{"@type":"BreadcrumbList","@id":"https:\/\/ptifa.com\/p\/courses\/level-4-team-training\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ptifa.com\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/ptifa.com\/fr\/produits\/"},{"@type":"ListItem","position":3,"name":"Dermal Filler Team Fundamentals"}]},{"@type":"WebSite","@id":"https:\/\/ptifa.com\/fr\/#website","url":"https:\/\/ptifa.com\/fr\/","name":"Institut de formation du Pacifique pour l'esth\u00e9tique faciale et la th\u00e9rapeutique","description":"","publisher":{"@id":"https:\/\/ptifa.com\/fr\/#organization"},"alternateName":"PTIFAT","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ptifa.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/ptifa.com\/fr\/#organization","name":"Institut de formation du Pacifique pour l'esth\u00e9tique faciale et la th\u00e9rapeutique","alternateName":"PTIFAT","url":"https:\/\/ptifa.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/ptifa.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/ptifa-logo.svg","contentUrl":"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/ptifa-logo.svg","width":310,"height":42,"caption":"Pacific Training Institute for Facial Aesthetics & Therapeutics"},"image":{"@id":"https:\/\/ptifa.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/ptifa.com\/fr\/wp-json\/wp\/v2\/product\/3037","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ptifa.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ptifa.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ptifa.com\/fr\/wp-json\/wp\/v2\/media\/3007"}],"wp:attachment":[{"href":"https:\/\/ptifa.com\/fr\/wp-json\/wp\/v2\/media?parent=3037"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ptifa.com\/fr\/wp-json\/wp\/v2\/product_brand?post=3037"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ptifa.com\/fr\/wp-json\/wp\/v2\/product_cat?post=3037"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ptifa.com\/fr\/wp-json\/wp\/v2\/product_tag?post=3037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}