{"id":3041,"date":"2025-03-30T00:58:09","date_gmt":"2025-03-30T00:58:09","guid":{"rendered":"https:\/\/ptifa.com\/?post_type=product&#038;p=3041"},"modified":"2025-07-13T21:14:39","modified_gmt":"2025-07-13T21:14:39","slug":"cours-de-recyclage-botox","status":"publish","type":"product","link":"https:\/\/ptifa.com\/fr\/p\/courses\/botox-refresher-course\/","title":{"rendered":"Cours de recyclage Botox\u00ae"},"content":{"rendered":"<div>\n<h2 class=\"gb-text gb-text-e33c0b94\">Ce que vous apprendrez<\/h2>\n\n\n\n<p class=\"gb-text gb-text-66279411\"><img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"12\" class=\"wp-image-944\" style=\"width: 16px;\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/bullet-point.svg\" alt=\"\"> Assister \u00e0 un <strong>laboratoire int\u00e9gr\u00e9 de cadavres et pratiquer la technique de rep\u00e9rage<\/strong> pour la mise en place de sites d'injection pr\u00e9cis dans la partie sup\u00e9rieure du visage et pour les PTM.<\/p>\n\n\n\n<p class=\"gb-text\"><img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"12\" class=\"wp-image-944\" style=\"width: 16px;\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/bullet-point.svg\" alt=\"\"> R\u00e9tablir la confiance avec le <strong>PTIFAT Technique d'injection de sels<\/strong> apr\u00e8s avoir observ\u00e9 le Dr Roberts injecter un mod\u00e8le vivant.<\/p>\n\n\n\n<h2 class=\"gb-text gb-text-d3457885\">Rencontre avec le directeur clinique<\/h2>\n\n\n\n<div class=\"gb-element-b05ca458\">\n<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"205\" class=\"gb-media-48d61828\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/dr-warren-roberts-.jpg\" title=\"dr-warren-roberts-\"\/>\n\n\n\n<div class=\"gb-element-3102305d\">\n<h4 class=\"gb-text gb-text-543d74b4\">Dr. Warren Roberts<\/h4>\n\n\n\n<p class=\"gb-text gb-text-0f7e1770\">Cofondateur et directeur clinique<\/p>\n\n\n\n<p class=\"gb-text gb-text-bda9298c small-text\">Le Dr Warren Roberts est le cofondateur et le directeur clinique du Pacific Training Institute for Facial Aesthetics and Therapeutics. Il est professeur clinicien \u00e0 la retraite au d\u00e9partement des sciences de la sant\u00e9 bucco-dentaire de l'universit\u00e9 de Colombie-Britannique.&nbsp; <span style=\"text-decoration: underline;\">Plus d'informations<\/span> <span style=\"text-decoration: underline;\"><img loading=\"lazy\" decoding=\"async\" width=\"10\" height=\"6\" class=\"wp-image-2748\" style=\"width: 10px;\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/arrow-down.svg\" alt=\"\"><\/span><\/p>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"gb-text gb-text-39e14c6a\">D\u00e9tails du cours<\/h2>\n\n\n\n<p class=\"gb-text gb-text-7f6e74e3\">Le cours de recyclage Botox\u00ae est une session pratique d'une journ\u00e9e (8 heures) et a \u00e9t\u00e9 d\u00e9velopp\u00e9 pour ceux qui ont pr\u00e9c\u00e9demment suivi les niveaux 1 et 2 de la formation, mais qui n'ont pas fait d'injections r\u00e9cemment. Reprenez confiance en pratiquant la technique de rep\u00e9rage PTIFAT pour placer des sites d'injection pr\u00e9cis, ainsi que la technique d'injection PTIFAT.<\/p>\n\n\n\n<div class=\"gb-element-073743c6 dashed-left\">\n<h3 class=\"gb-text gb-text-a35c5bc5\">Session pratique<\/h3>\n\n\n\n<div class=\"gb-element-d8898d4a\">\n<figure class=\"wp-block-image size-large image-fit-height\"><img loading=\"lazy\" decoding=\"async\" width=\"23\" height=\"23\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/clinical.svg\" alt=\"Ic\u00f4ne clinique pratique.\" class=\"wp-image-3650\"\/><\/figure>\n\n\n\n<div>\n<h5 class=\"gb-text gb-text-8cb9bdc9\">Laboratoire de rep\u00e9rage int\u00e9gratif des cadavres<\/h5>\n\n\n\n<p class=\"gb-text small-text\">Le cours commence par une s\u00e9ance d'int\u00e9gration sur cadavre au cours de laquelle le Dr Roberts passe en revue de mani\u00e8re approfondie l'anatomie pertinente pour la mise en place de la toxine botulique et relie les caract\u00e9ristiques des surfaces \u00e0 la musculature et aux os sous-jacents. Vous aurez l'occasion de pratiquer la technique de rep\u00e9rage anatomique PTIFAT sur un partenaire pendant que chaque muscle est soigneusement examin\u00e9 sur un cadavre. Le Dr Roberts utilisera les mod\u00e8les et la technique d'injection th\u00e9rapeutique et esth\u00e9tique PTIFAT pour obtenir des r\u00e9sultats pr\u00e9visibles et des effets secondaires minimes.<\/p>\n\n\n\n<div class=\"gb-element-d1041d92\" id=\"day-1\">\n<p class=\"gb-text small-text\">La compr\u00e9hension de la source, des voies et du chevauchement des nerfs cr\u00e2niens constitue la base de la compr\u00e9hension de la douleur myofaciale et de la synergie qui existe entre la th\u00e9rapie esth\u00e9tique et la th\u00e9rapie par la toxine botulique.<\/p>\n<\/div>\n\n\n\n<a class=\"gb-text-f470a832 small-text see-more\" data-pointer=\"day-1\"><span class=\"gb-text\">Afficher la journ\u00e9e compl\u00e8te<\/span><span class=\"gb-shape\"><svg width=\"10\" height=\"6\" viewbox=\"0 0 10 6\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M8.95291 0L4.98459 3.7072L0.992079 0.0236128L0 0.991736L4.9604 5.71429L9.99339 1.01535L8.95291 0Z\" fill=\"#164550\"><\/path>\n<\/svg>\n<\/span><\/a>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"gb-text gb-text-be2ba05f\">\u00c0 quoi s'attendre<\/h2>\n\n\n\n<div class=\"gb-element-fd4d8d54\">\n<div class=\"gb-element-37f2b3c0\">\n<a href=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/pgallery-1.jpg\" data-lightbox=\"expectation\"><img loading=\"lazy\" decoding=\"async\" width=\"928\" height=\"576\" class=\"gb-media-56a80a1a\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/pgallery-1.jpg\" title=\"pgallery-1\" srcset=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/pgallery-1.jpg 928w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/pgallery-1-300x186.jpg 300w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/pgallery-1-768x477.jpg 768w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/pgallery-1-600x372.jpg 600w\" sizes=\"auto, (max-width: 928px) 100vw, 928px\" \/><\/a>\n<\/div>\n\n\n\n<div class=\"gb-element-bbe09f31\">\n<a href=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/pgallery-2.jpg\" data-lightbox=\"expectation\"><img loading=\"lazy\" decoding=\"async\" width=\"932\" height=\"576\" class=\"gb-media-5f9869f0\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/pgallery-2.jpg\" title=\"pgallery-2\" srcset=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/pgallery-2.jpg 932w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/pgallery-2-300x185.jpg 300w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/pgallery-2-768x475.jpg 768w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/pgallery-2-600x371.jpg 600w\" sizes=\"auto, (max-width: 932px) 100vw, 932px\" \/><\/a>\n<\/div>\n\n\n\n<div class=\"gb-element-96a7cd29\">\n<a href=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/pgallery-3.jpg\" data-lightbox=\"expectation\"><img loading=\"lazy\" decoding=\"async\" width=\"928\" height=\"576\" class=\"gb-media-bb9bfc41\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/pgallery-3.jpg\" title=\"pgallery-3\" srcset=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/pgallery-3.jpg 928w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/pgallery-3-300x186.jpg 300w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/pgallery-3-768x477.jpg 768w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/pgallery-3-600x372.jpg 600w\" sizes=\"auto, (max-width: 928px) 100vw, 928px\" \/><\/a>\n<\/div>\n\n\n\n<div class=\"gb-element-6ff96619\">\n<a href=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/pgallery-4.jpg\" data-lightbox=\"expectation\"><img loading=\"lazy\" decoding=\"async\" width=\"928\" height=\"576\" class=\"gb-media-f4090a9d\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/pgallery-4.jpg\" title=\"pgallery-4\" srcset=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/pgallery-4.jpg 928w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/pgallery-4-300x186.jpg 300w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/pgallery-4-768x477.jpg 768w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/pgallery-4-600x372.jpg 600w\" sizes=\"auto, (max-width: 928px) 100vw, 928px\" \/><\/a>\n<\/div>\n\n\n\n<div class=\"gb-element-b5bafb00\">\n<a href=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/pgallery-5.jpg\" data-lightbox=\"expectation\"><img loading=\"lazy\" decoding=\"async\" width=\"932\" height=\"576\" class=\"gb-media-cfb466e7\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/pgallery-5.jpg\" title=\"pgallery-5\" srcset=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/pgallery-5.jpg 932w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/pgallery-5-300x185.jpg 300w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/pgallery-5-768x475.jpg 768w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/pgallery-5-600x371.jpg 600w\" sizes=\"auto, (max-width: 932px) 100vw, 932px\" \/><\/a>\n<\/div>\n\n\n\n<div class=\"gb-element-6ed9b24f\">\n<a href=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/pgallery-6.jpg\" data-lightbox=\"expectation\"><img loading=\"lazy\" decoding=\"async\" width=\"928\" height=\"576\" class=\"gb-media-76090754\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/pgallery-6.jpg\" title=\"pgallery-6\" srcset=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/pgallery-6.jpg 928w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/pgallery-6-300x186.jpg 300w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/pgallery-6-768x477.jpg 768w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/pgallery-6-600x372.jpg 600w\" sizes=\"auto, (max-width: 928px) 100vw, 928px\" \/><\/a>\n<\/div>\n<\/div>\n\n\n\n<h6 class=\"gb-text gb-text-3be91919\">Retrouver la confiance gr\u00e2ce au marquage des zones de traitement suivantes :<\/h6>\n\n\n\n<div class=\"gb-element-53a58da2\">\n<div class=\"gb-element-51eb8965\">\n<img loading=\"lazy\" decoding=\"async\" width=\"289\" height=\"210\" class=\"gb-media-b084cfb7 image-auto-height-content\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/image-48.jpg\" title=\"image 48\"\/>\n\n\n\n<p class=\"gb-text gb-text-256a1985 small-strong\">Complexe de la glabelle<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-058d023c\">\n<img loading=\"lazy\" decoding=\"async\" width=\"289\" height=\"210\" class=\"gb-media-824565ba image-auto-height-content\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/image-49.jpg\" title=\"image 49\"\/>\n\n\n\n<p class=\"gb-text gb-text-a9b9a9a4 small-strong\">Frontalis<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-056f53ce\">\n<img loading=\"lazy\" decoding=\"async\" width=\"289\" height=\"210\" class=\"gb-media-75d2428e image-auto-height-content\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/image-49.jpg\" title=\"image 49\"\/>\n\n\n\n<p class=\"gb-text gb-text-cb1ce34d small-strong\">Migraines et maux de t\u00eate<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-8e19ca27\">\n<img loading=\"lazy\" decoding=\"async\" width=\"289\" height=\"210\" class=\"gb-media-1a05c12b image-auto-height-content\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/image-51.jpg\" title=\"image 51\"\/>\n\n\n\n<p class=\"gb-text gb-text-5c1e6961 small-strong\">Orbicularis Occuli<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-64b3de63\">\n<img loading=\"lazy\" decoding=\"async\" width=\"289\" height=\"210\" class=\"gb-media-328ef370 image-auto-height-content\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/image-52.jpg\" title=\"image 52\"\/>\n\n\n\n<p class=\"gb-text gb-text-dff08639 small-strong\">Habitudes parafonctionnelles&nbsp;<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-f7a6797d\">\n<img loading=\"lazy\" decoding=\"async\" width=\"532\" height=\"375\" class=\"gb-media-f1e7409f image-auto-height-content\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/Therapeutic-no-blood-cropped.webp\" title=\"Th\u00e9rapeutique-sans-sang-crois\u00e9\" alt=\"Femme recevant des injections de Botox dans son mass\u00e9ter pour des douleurs de type TMD.\" srcset=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/Therapeutic-no-blood-cropped.webp 532w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/Therapeutic-no-blood-cropped-300x211.webp 300w\" sizes=\"auto, (max-width: 532px) 100vw, 532px\" \/>\n\n\n\n<p class=\"gb-text gb-text-ee3e4d36 small-strong\">TMD<\/p>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"gb-text gb-text-43f2f47e\">Ce cours est id\u00e9al pour<\/h2>\n\n\n\n<div class=\"gb-element-b3183b32\">\n<div class=\"gb-element-08c7d390\">\n<img loading=\"lazy\" decoding=\"async\" width=\"933\" height=\"914\" class=\"gb-media-8594454c\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/dentists.jpg\" title=\"dentistes\" srcset=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/dentists.jpg 933w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/dentists-300x294.jpg 300w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/dentists-768x752.jpg 768w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/dentists-600x588.jpg 600w\" sizes=\"auto, (max-width: 933px) 100vw, 933px\" \/>\n\n\n\n<div class=\"gb-element-f6dd379a\">\n<h5 class=\"gb-text gb-text-34797e4a\">Dentistes<\/h5>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-21dfbfde\">\n<img loading=\"lazy\" decoding=\"async\" width=\"614\" height=\"941\" class=\"gb-media-590231ed\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/Physicians.webp\" title=\"M\u00e9decins\" srcset=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/Physicians.webp 614w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/Physicians-196x300.webp 196w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/Physicians-600x920.webp 600w\" sizes=\"auto, (max-width: 614px) 100vw, 614px\" \/>\n\n\n\n<div class=\"gb-element-6cddb54e\">\n<h5 class=\"gb-text gb-text-4fb1629b\">M\u00e9decins<\/h5>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-ce6c28d6\">\n<img loading=\"lazy\" decoding=\"async\" width=\"609\" height=\"948\" class=\"gb-media-da6c4f99\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/Nurses.webp\" title=\"Infirmiers\" srcset=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/Nurses.webp 609w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/Nurses-193x300.webp 193w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/Nurses-600x934.webp 600w\" sizes=\"auto, (max-width: 609px) 100vw, 609px\" \/>\n\n\n\n<div class=\"gb-element-a2f1f493\">\n<h5 class=\"gb-text gb-text-79ea433e\">Infirmiers<\/h5>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-3ea9682c\">\n<h5 class=\"gb-text gb-text-a68ee59c\">Formation du personnel de soutien clinique<\/h5>\n\n\n\n<p class=\"gb-text gb-text-2adad30b small-text\">Nous proposons un <a href=\"\/fr\/p\/cours\/niveau-2-botox-de-base-fr\/\">Niveau 2 - Formation d'\u00e9quipe <\/a>pour les membres de l'\u00e9quipe qui ne sont pas des injecteurs, ax\u00e9 sur les comp\u00e9tences cliniques, l'int\u00e9gration et le marketing, qui se tient en m\u00eame temps que la formation des praticiens.<\/p>\n<\/div>\n\n\n\n<h2 class=\"gb-text gb-text-56f54e79\">Frais et exigences<\/h2>\n\n\n\n<div>\n<div class=\"gb-element-40d27b58\">\n<div class=\"gb-element-c03a3c48\">\n<p class=\"gb-text gb-text-e98569bf\">Frais de scolarit\u00e9 pour les praticiens :<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-083cc620\">\n<p class=\"gb-text\">$999 CAD (plus TPS)<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-a85ec567\">\n<div class=\"gb-element-f171b6f6\">\n<p class=\"gb-text gb-text-d8e23b64\">Pr\u00e9-requis :<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-6d3a8cf8\">\n<p class=\"gb-text\">L'ach\u00e8vement pr\u00e9alable des niveaux 1 et 2 est requis.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-8267191e\">\n<img loading=\"lazy\" decoding=\"async\" width=\"227\" height=\"155\" class=\"gb-media-6babbbf3\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/chart-fr.svg\" title=\"tableau\"\/>\n\n\n\n<div>\n<h2 class=\"gb-text gb-text-0d7560a7\">30%*<\/h2>\n\n\n\n<h4 class=\"gb-text gb-text-63d173bd\">croissance des recettes<\/h4>\n\n\n\n<p class=\"gb-text gb-text-a3c7dcb3 small-text\">* Les praticiens form\u00e9s par PTIFAT voient leurs revenus annuels augmenter de 30% au cours de la premi\u00e8re ann\u00e9e.<\/p>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"gb-text gb-text-f3336b59\">Avant et apr\u00e8s<\/h2>\n\n\n\n<p class=\"gb-text\">Voici les r\u00e9sultats typiques avant et apr\u00e8s que vous pouvez esp\u00e9rer obtenir apr\u00e8s avoir suivi le cours de niveau 2 - Botox\u00ae de base. Le niveau 2 couvre \u00e0 la fois l'utilisation esth\u00e9tique de la toxine botulique dans la partie sup\u00e9rieure du visage et l'utilisation th\u00e9rapeutique pour traiter les douleurs myofasciales (migraines\/c\u00e9phal\u00e9es\/TMD).<\/p>\n\n\n\n<div class=\"gb-tabs gb-tabs-2601df76\" data-opened-tab=\"1\">\n<div class=\"gb-tabs__menu gb-tabs__menu-53d3b85f\" role=\"list\">\n<div tabindex=\"0\" class=\"gb-tabs__menu-item gb-tabs__menu-item-07a8605c gb-block-is-current\" role=\"tab\" id=\"gb-tab-menu-item-07a8605c\" aria-selected=\"true\">\n<span class=\"gb-text small-text\">Front<\/span>\n<\/div>\n\n\n\n<div tabindex=\"0\" class=\"gb-tabs__menu-item gb-tabs__menu-item-e1481337\" role=\"tab\" id=\"gb-tab-menu-item-e1481337\">\n<span class=\"gb-text small-text\">Browlift<\/span>\n<\/div>\n\n\n\n<div tabindex=\"0\" class=\"gb-tabs__menu-item gb-tabs__menu-item-fc666777\" role=\"tab\" id=\"gb-tab-menu-item-fc666777\">\n<span class=\"gb-text small-text\">Mass\u00e9ter<\/span>\n<\/div>\n\n\n\n<div tabindex=\"0\" class=\"gb-tabs__menu-item gb-tabs__menu-item-77e99e5d\" role=\"tab\" id=\"gb-tab-menu-item-77e99e5d\">\n<span class=\"gb-text small-text\">Orbicularis Oculi<\/span>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-tabs__items\" role=\"tabpanel\">\n<div class=\"gb-tabs__item gb-tabs__item-79b95c43 gb-tabs__item-open\" id=\"gb-tab-item-79b95c43\">\n<div class=\"gb-element-3fdabde7\">\n<a href=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead1.jpg\" data-lightbox=\"forehead\"><img loading=\"lazy\" decoding=\"async\" width=\"1441\" height=\"461\" class=\"gb-media-107c8221\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead1.jpg\" title=\"front1\" srcset=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead1.jpg 1441w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead1-300x96.jpg 300w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead1-1024x328.jpg 1024w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead1-768x246.jpg 768w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead1-600x192.jpg 600w\" sizes=\"auto, (max-width: 1441px) 100vw, 1441px\" \/><\/a>\n\n\n\n<a href=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead2.jpg\" data-lightbox=\"forehead\"><img loading=\"lazy\" decoding=\"async\" width=\"1465\" height=\"469\" class=\"gb-media-944dd730\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead2.jpg\" title=\"front2\" srcset=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead2.jpg 1465w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead2-300x96.jpg 300w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead2-1024x328.jpg 1024w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead2-768x246.jpg 768w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead2-600x192.jpg 600w\" sizes=\"auto, (max-width: 1465px) 100vw, 1465px\" \/><\/a>\n\n\n\n<a href=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead3.jpg\" data-lightbox=\"forehead\"><img loading=\"lazy\" decoding=\"async\" width=\"1438\" height=\"462\" class=\"gb-media-00447f85\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead3.jpg\" title=\"front3\" srcset=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead3.jpg 1438w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead3-300x96.jpg 300w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead3-1024x329.jpg 1024w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead3-768x247.jpg 768w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead3-600x193.jpg 600w\" sizes=\"auto, (max-width: 1438px) 100vw, 1438px\" \/><\/a>\n\n\n\n<a href=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead4.jpg\" data-lightbox=\"forehead\"><img loading=\"lazy\" decoding=\"async\" width=\"1465\" height=\"462\" class=\"gb-media-381bb439\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead4.jpg\" title=\"front4\" srcset=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead4.jpg 1465w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead4-300x95.jpg 300w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead4-1024x323.jpg 1024w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead4-768x242.jpg 768w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead4-600x189.jpg 600w\" sizes=\"auto, (max-width: 1465px) 100vw, 1465px\" \/><\/a>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-tabs__item\" id=\"gb-tab-item-2a5af105\">\n<div class=\"gb-element-ce4e8efd\">\n<img loading=\"lazy\" decoding=\"async\" width=\"1438\" height=\"462\" class=\"gb-media-4028f18c\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead3.jpg\" title=\"front3\" srcset=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead3.jpg 1438w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead3-300x96.jpg 300w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead3-1024x329.jpg 1024w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead3-768x247.jpg 768w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead3-600x193.jpg 600w\" sizes=\"auto, (max-width: 1438px) 100vw, 1438px\" \/>\n\n\n\n<img loading=\"lazy\" decoding=\"async\" width=\"1441\" height=\"461\" class=\"gb-media-0fd391b5\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead1.jpg\" title=\"front1\" srcset=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead1.jpg 1441w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead1-300x96.jpg 300w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead1-1024x328.jpg 1024w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead1-768x246.jpg 768w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead1-600x192.jpg 600w\" sizes=\"auto, (max-width: 1441px) 100vw, 1441px\" \/>\n\n\n\n<img loading=\"lazy\" decoding=\"async\" width=\"1465\" height=\"469\" class=\"gb-media-e609ebdc\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead2.jpg\" title=\"front2\" srcset=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead2.jpg 1465w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead2-300x96.jpg 300w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead2-1024x328.jpg 1024w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead2-768x246.jpg 768w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead2-600x192.jpg 600w\" sizes=\"auto, (max-width: 1465px) 100vw, 1465px\" \/>\n\n\n\n<img loading=\"lazy\" decoding=\"async\" width=\"1465\" height=\"462\" class=\"gb-media-a5d4b249\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead4.jpg\" title=\"front4\" srcset=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead4.jpg 1465w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead4-300x95.jpg 300w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead4-1024x323.jpg 1024w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead4-768x242.jpg 768w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead4-600x189.jpg 600w\" sizes=\"auto, (max-width: 1465px) 100vw, 1465px\" \/>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-tabs__item\" id=\"gb-tab-item-8c1dc25c\">\n<div class=\"gb-element-d5a47a2a\">\n<img loading=\"lazy\" decoding=\"async\" width=\"1465\" height=\"469\" class=\"gb-media-495e6d48\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead2.jpg\" title=\"front2\" srcset=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead2.jpg 1465w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead2-300x96.jpg 300w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead2-1024x328.jpg 1024w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead2-768x246.jpg 768w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead2-600x192.jpg 600w\" sizes=\"auto, (max-width: 1465px) 100vw, 1465px\" \/>\n\n\n\n<img loading=\"lazy\" decoding=\"async\" width=\"1438\" height=\"462\" class=\"gb-media-6e4085e1\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead3.jpg\" title=\"front3\" srcset=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead3.jpg 1438w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead3-300x96.jpg 300w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead3-1024x329.jpg 1024w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead3-768x247.jpg 768w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead3-600x193.jpg 600w\" sizes=\"auto, (max-width: 1438px) 100vw, 1438px\" \/>\n\n\n\n<img loading=\"lazy\" decoding=\"async\" width=\"1441\" height=\"461\" class=\"gb-media-cc0545f9\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead1.jpg\" title=\"front1\" srcset=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead1.jpg 1441w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead1-300x96.jpg 300w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead1-1024x328.jpg 1024w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead1-768x246.jpg 768w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead1-600x192.jpg 600w\" sizes=\"auto, (max-width: 1441px) 100vw, 1441px\" \/>\n\n\n\n<img loading=\"lazy\" decoding=\"async\" width=\"1465\" height=\"462\" class=\"gb-media-d412a1c6\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead4.jpg\" title=\"front4\" srcset=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead4.jpg 1465w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead4-300x95.jpg 300w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead4-1024x323.jpg 1024w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead4-768x242.jpg 768w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead4-600x189.jpg 600w\" sizes=\"auto, (max-width: 1465px) 100vw, 1465px\" \/>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-tabs__item\" id=\"gb-tab-item-f7190802\">\n<div class=\"gb-element-f1914f45\">\n<img loading=\"lazy\" decoding=\"async\" width=\"1465\" height=\"462\" class=\"gb-media-eb7ac9ce\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead4.jpg\" title=\"front4\" srcset=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead4.jpg 1465w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead4-300x95.jpg 300w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead4-1024x323.jpg 1024w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead4-768x242.jpg 768w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead4-600x189.jpg 600w\" sizes=\"auto, (max-width: 1465px) 100vw, 1465px\" \/>\n\n\n\n<img loading=\"lazy\" decoding=\"async\" width=\"1465\" height=\"469\" class=\"gb-media-a027159e\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead2.jpg\" title=\"front2\" srcset=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead2.jpg 1465w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead2-300x96.jpg 300w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead2-1024x328.jpg 1024w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead2-768x246.jpg 768w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead2-600x192.jpg 600w\" sizes=\"auto, (max-width: 1465px) 100vw, 1465px\" \/>\n\n\n\n<img loading=\"lazy\" decoding=\"async\" width=\"1438\" height=\"462\" class=\"gb-media-aaba3739\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead3.jpg\" title=\"front3\" srcset=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead3.jpg 1438w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead3-300x96.jpg 300w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead3-1024x329.jpg 1024w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead3-768x247.jpg 768w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead3-600x193.jpg 600w\" sizes=\"auto, (max-width: 1438px) 100vw, 1438px\" \/>\n\n\n\n<img loading=\"lazy\" decoding=\"async\" width=\"1441\" height=\"461\" class=\"gb-media-fdea25bc\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead1.jpg\" title=\"front1\" srcset=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead1.jpg 1441w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead1-300x96.jpg 300w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead1-1024x328.jpg 1024w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead1-768x246.jpg 768w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/forehead1-600x192.jpg 600w\" sizes=\"auto, (max-width: 1441px) 100vw, 1441px\" \/>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"gb-text gb-text-8961e368\">FAQ du cours<\/h2>\n\n\n\n<div class=\"gb-accordion gb-accordion-e13a3377\">\n<div class=\"gb-accordion__item gb-accordion__item-03cc4db3\">\n<div role=\"button\" tabindex=\"0\" class=\"gb-accordion__toggle gb-accordion__toggle-dec3ecaa\" id=\"gb-accordion-toggle-dec3ecaa\">\n<span class=\"gb-text gb-text-469ab87b\">I&#8217;ve taken another Botox\u00ae course, can I register for the Botox Refresher Course?<\/span>\n\n\n\n<span class=\"gb-accordion__toggle-icon gb-accordion__toggle-icon-09d9537b\"><span class=\"gb-accordion__toggle-icon-open\"><svg aria-hidden=\"true\" viewbox=\"0 0 256 256\"><rect width=\"256\" height=\"256\" fill=\"none\"><\/rect><polyline points=\"208 96 128 176 48 96\" fill=\"none\" stroke=\"currentColor\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"16\"><\/polyline><\/svg><\/span><span class=\"gb-accordion__toggle-icon-close\"><svg aria-hidden=\"true\" viewbox=\"0 0 256 256\"><rect width=\"256\" height=\"256\" fill=\"none\"><\/rect><polyline points=\"48 160 128 80 208 160\" fill=\"none\" stroke=\"currentColor\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"16\"><\/polyline><\/svg><\/span><\/span>\n<\/div>\n\n\n\n<div class=\"gb-accordion__content\" id=\"gb-accordion-content-732ab659\">\n<div class=\"gb-element-eceab857\">\n<p>This course has been designed for PTIFAT graduates who have previously completed Level 1 &amp; Level 2, but haven&#8217;t been injecting lately. We highly recommend taking your training to the next level by registering for the Level 1 and Level 2 course. You can also access your level of knowledge by completing our <a href=\"https:\/\/ptifa.com\/fr\/quiz-sur-le-botox\/\">Test de QI Botox gratuit en ligne<\/a>. <\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-accordion__item gb-accordion__item-2259b751\">\n<div role=\"button\" tabindex=\"0\" class=\"gb-accordion__toggle gb-accordion__toggle-adf6c0d6\" id=\"gb-accordion-toggle-adf6c0d6\">\n<span class=\"gb-text gb-text-89230ad9\">Puis-je me faire accompagner par un membre de mon \u00e9quipe ou de mon personnel ?<\/span>\n\n\n\n<span class=\"gb-accordion__toggle-icon gb-accordion__toggle-icon-6b8d7191\"><span class=\"gb-accordion__toggle-icon-open\"><svg aria-hidden=\"true\" viewbox=\"0 0 256 256\"><rect width=\"256\" height=\"256\" fill=\"none\"><\/rect><polyline points=\"208 96 128 176 48 96\" fill=\"none\" stroke=\"currentColor\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"16\"><\/polyline><\/svg><\/span><span class=\"gb-accordion__toggle-icon-close\"><svg aria-hidden=\"true\" viewbox=\"0 0 256 256\"><rect width=\"256\" height=\"256\" fill=\"none\"><\/rect><polyline points=\"48 160 128 80 208 160\" fill=\"none\" stroke=\"currentColor\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"16\"><\/polyline><\/svg><\/span><\/span>\n<\/div>\n\n\n\n<div class=\"gb-accordion__content\" id=\"gb-accordion-content-c2a3f650\">\n<div class=\"gb-element-315c5fa6\">\n<p>Ce cours est r\u00e9serv\u00e9 aux praticiens, mais nous proposons des cours distincts destin\u00e9s sp\u00e9cifiquement aux membres de l'\u00e9quipe. <a href=\"https:\/\/ptifa.com\/fr\/p\/cours\/formation-dequipe-de-niveau-2\/\">Cliquez ici pour plus d'informations<\/a>.<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-accordion__item gb-accordion__item-6fbb6486\">\n<div role=\"button\" tabindex=\"0\" class=\"gb-accordion__toggle gb-accordion__toggle-351a3644\" id=\"gb-accordion-toggle-351a3644\">\n<span class=\"gb-text gb-text-22df329c\">Il se peut que je veuille assister aux travaux pratiques cliniques et faire des injections avec un instructeur. Puis-je \u00e9galement assister au jour 2 \u00e0 la clinique ?<\/span>\n\n\n\n<span class=\"gb-accordion__toggle-icon gb-accordion__toggle-icon-ce8d0e14\"><span class=\"gb-accordion__toggle-icon-open\"><svg aria-hidden=\"true\" viewbox=\"0 0 256 256\"><rect width=\"256\" height=\"256\" fill=\"none\"><\/rect><polyline points=\"208 96 128 176 48 96\" fill=\"none\" stroke=\"currentColor\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"16\"><\/polyline><\/svg><\/span><span class=\"gb-accordion__toggle-icon-close\"><svg aria-hidden=\"true\" viewbox=\"0 0 256 256\"><rect width=\"256\" height=\"256\" fill=\"none\"><\/rect><polyline points=\"48 160 128 80 208 160\" fill=\"none\" stroke=\"currentColor\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"16\"><\/polyline><\/svg><\/span><\/span>\n<\/div>\n\n\n\n<div class=\"gb-accordion__content\" id=\"gb-accordion-content-9b07d237\">\n<div class=\"gb-element-16c52e5e\">\n<p>Oui, il est possible que nous puissions vous accueillir, mais les places dans la clinique sont limit\u00e9es et d\u00e9pendent de la disponibilit\u00e9. Veuillez nous contacter pour plus de d\u00e9tails. Des frais suppl\u00e9mentaires s'appliqueront pour assister \u00e0 la clinique pratique.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"gb-text gb-text-cfdcea2d\">Vous avez encore une question ?<\/h2>\n\n\n\n<div class=\"gb-element-770c675a\">\n<div class=\"gb-element-f38c39cc\">\n<img loading=\"lazy\" decoding=\"async\" width=\"56\" height=\"56\" class=\"gb-media-b87dbeb7\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/phone-1.svg\" title=\"t\u00e9l\u00e9phone-1\"\/>\n\n\n\n<div>\n<h6 class=\"gb-text gb-text-848b6a13\">Nous contacter<\/h6>\n\n\n\n<p class=\"gb-text gb-text-79181dbf small-link\"><a href=\"https:\/\/ptifa.com\/fr\/nous-contacter\/\">Envoyer un message<\/a><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-eed5f3f9\">\n<img loading=\"lazy\" decoding=\"async\" width=\"56\" height=\"56\" class=\"gb-media-b645dc7b\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/phone-2.svg\" title=\"t\u00e9l\u00e9phone-2\"\/>\n\n\n\n<div>\n<h6 class=\"gb-text gb-text-ba2b8604\">Appelez-nous<\/h6>\n\n\n\n<p class=\"gb-text gb-text-a85f42dd small-link\"><a href=\"tel:18556810066\">1-855-681-0066<\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"gb-text gb-text-03c9e80b\">Reconnaissance et accr\u00e9ditation CE\/CME<\/h2>\n\n\n\n<p class=\"gb-text\">PTIFAT est un prestataire reconnu par l'ADA CERP. L'ADA CERP est un service de l'American Dental Association qui aide les professionnels dentaires \u00e0 identifier les prestataires de qualit\u00e9 en mati\u00e8re de formation dentaire continue.<\/p>\n\n\n\n<p class=\"gb-text gb-text-8bf4fe34\">Le CERP de l'ADA n'approuve ni ne soutient les cours individuels ou les instructeurs, et n'implique pas non plus l'acceptation des heures de cr\u00e9dit par les conseils de l'ordre des dentistes. PTIFAT d\u00e9signe le cours de recyclage Botox\u00ae pour 8 heures de cr\u00e9dits de formation continue.<\/p>\n\n\n\n<div class=\"gb-element-40564722\">\n<div class=\"gb-element-c17da12f\">\n<img loading=\"lazy\" decoding=\"async\" width=\"499\" height=\"128\" class=\"gb-media-607e272b\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/ada-fr.webp\" title=\"ada-cerp-banner\" srcset=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/ada-fr.webp 1257w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/ada-fr-300x66.webp 300w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/ada-fr-1024x225.webp 1024w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/ada-fr-768x169.webp 768w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/ada-fr-18x4.webp 18w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/ada-fr-600x132.webp 600w\" sizes=\"auto, (max-width: 499px) 100vw, 499px\" \/>\n<\/div>\n\n\n\n<div class=\"gb-element-827479a9\">\n<img loading=\"lazy\" decoding=\"async\" width=\"476\" height=\"128\" class=\"gb-media-bbfb96be\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/rep-fr-1.webp\" title=\"reconnu-\u00e9ducatif\" srcset=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/rep-fr-1.webp 819w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/rep-fr-1-300x67.webp 300w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/rep-fr-1-768x172.webp 768w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/rep-fr-1-18x4.webp 18w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/10\/rep-fr-1-600x134.webp 600w\" sizes=\"auto, (max-width: 476px) 100vw, 476px\" \/>\n<\/div>\n\n\n\n<div class=\"gb-element-6d9b1ae6\">\n<img loading=\"lazy\" decoding=\"async\" width=\"844\" height=\"528\" class=\"gb-media-1a278e5a\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/aogd-q.webp\" title=\"aogd-q\" srcset=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/aogd-q.webp 844w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/aogd-q-300x188.webp 300w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/aogd-q-768x480.webp 768w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/aogd-q-600x375.webp 600w\" sizes=\"auto, (max-width: 844px) 100vw, 844px\" \/>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"gb-text gb-text-5a5d8e23\">Les r\u00e9ussites de nos dipl\u00f4m\u00e9s<\/h2>\n\n\n\n<div class=\"gb-element-55a13d46\">\n<p class=\"gb-text gb-text-c37aa262\">5.0 <img loading=\"lazy\" decoding=\"async\" width=\"77\" height=\"13\" class=\"wp-image-1024\" style=\"width: 77px;\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/5-stars.svg\" alt=\"\"> (250+ commentaires)<\/p>\n\n\n\n<p class=\"gb-text gb-text-8604dc87\">+8 000 dipl\u00f4m\u00e9s<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-fe5fcd64\">\n<div class=\"gb-element-2d4ac503\">\n<h5 class=\"gb-text gb-text-4d9e92c8\">\"J'ai suivi ce cours il y a de nombreuses ann\u00e9es, et \u00e0 nouveau le week-end dernier. Il \u00e9tait fantastique dans le pass\u00e9, et le contenu n'a fait qu'\u00e9voluer et s'am\u00e9liorer. J'ai une grande exp\u00e9rience de l'injection, mais j'ai tout de m\u00eame acquis de nouvelles connaissances utiles et b\u00e9n\u00e9fiques. Pour un praticien d\u00e9butant les injections, comme pour quelqu'un qui le fait depuis des ann\u00e9es, ce cours est la r\u00e9f\u00e9rence en Am\u00e9rique du Nord et je le recommande vivement.<\/h5>\n\n\n\n<div class=\"gb-element-38c51242\">\n<div class=\"gb-element-0cc862da\">\n<img loading=\"lazy\" decoding=\"async\" width=\"90\" height=\"122\" class=\"gb-media-fa42a26b\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/Dr.VishalSharma2.jpg\" title=\"Dr. VishalSharma2\" alt=\"Dr. Vishal Sharma\"\/>\n\n\n\n<div>\n<h6 class=\"gb-text gb-text-6ae005bf\">Dr. Vishal Sharma (Dentiste)<\/h6>\n\n\n\n<p class=\"gb-text gb-text-ac68e961\">Calgary, AB<\/p>\n<\/div>\n<\/div>\n\n\n\n<a href=\"#\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"112\" height=\"116\" class=\"gb-media-7d54a387 image-auto-height-content\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/Google-Reviews-Icon.webp\" title=\"Ic\u00f4ne Google-Reviews\" alt=\"Avis de Google.\"\/><\/a>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-373aea02\">\n<h5 class=\"gb-text gb-text-8f9178e7\">\"Le cours du Dr Roberts est tr\u00e8s syst\u00e9matique et complet. Je me sens pr\u00eate \u00e0 commencer \u00e0 administrer le Botox dans mon cabinet imm\u00e9diatement apr\u00e8s le cours. Les ressources en ligne facilitent la pr\u00e9paration et l'\u00e9tude du cours \u00e0 l'avance.\"<\/h5>\n\n\n\n<div class=\"gb-element-7e73d2a9\">\n<div class=\"gb-element-fc56ceae\">\n<img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" class=\"gb-media-48dc047a\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/neda-refati.png\" title=\"neda-refati\" alt=\"Dr. Neda Refati\" srcset=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/neda-refati.png 120w, https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/neda-refati-100x100.png 100w\" sizes=\"auto, (max-width: 120px) 100vw, 120px\" \/>\n\n\n\n<div>\n<h6 class=\"gb-text gb-text-13267f8c\">Dr. Neda Refati (Dentiste)<\/h6>\n\n\n\n<p class=\"gb-text gb-text-8613c665\">Vancouver, BC<\/p>\n<\/div>\n<\/div>\n\n\n\n<a href=\"#\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"112\" height=\"116\" class=\"gb-media-86e5dc35 image-auto-height-content\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/Google-Reviews-Icon.webp\" title=\"Ic\u00f4ne Google-Reviews\" alt=\"Avis de Google.\"\/><\/a>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-d9c322e0\">\n<h5 class=\"gb-text gb-text-91d4cac9\">\"Le meilleur cours que j'ai suivi depuis l'obtention de mon dipl\u00f4me en 1996.<\/h5>\n\n\n\n<div class=\"gb-element-a7cbaa86\">\n<div class=\"gb-element-7539d331\">\n<img loading=\"lazy\" decoding=\"async\" width=\"78\" height=\"82\" class=\"gb-media-0661da41\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/Marianne-Stelmaschuk.jpg\" title=\"Marianne-Stelmaschuk\" alt=\"Dr. Marianne Stelmaschuk\"\/>\n\n\n\n<div>\n<h6 class=\"gb-text gb-text-cb905ba6\">Dr. Marianne Stelmaschuk (Dentiste)<\/h6>\n\n\n\n<div>\n<p class=\"gb-text gb-text-f938357a\">Lloydminster, AB<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<a href=\"#\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"20\" height=\"20\" class=\"gb-media-e64d9e36 image-auto-height-content\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/facebook-brands-solid-1.svg\" title=\"facebook-marques-solidaires 1\"\/><\/a>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-b600a684\">\n<h5 class=\"gb-text gb-text-6b6a5f90\">\"Une formation continue extr\u00eamement bien organis\u00e9e. L'un des meilleurs cours pratiques jamais organis\u00e9s !\"<\/h5>\n\n\n\n<div class=\"gb-element-b63d7166\">\n<div class=\"gb-element-baa901ec\">\n<img loading=\"lazy\" decoding=\"async\" width=\"116\" height=\"122\" class=\"gb-media-608c3fd4\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/Kenneth-Banks.jpg\" title=\"Kenneth-Banks\" alt=\"Dr. Kenneth Banks\"\/>\n\n\n\n<div>\n<h6 class=\"gb-text gb-text-09dce00e\">Dr. Kenneth Banks (Dentiste)<\/h6>\n\n\n\n<p class=\"gb-text gb-text-285ccd43\">Inwood, WV<\/p>\n<\/div>\n<\/div>\n\n\n\n<a href=\"#\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"20\" height=\"20\" class=\"gb-media-3e445bf7 image-auto-height-content\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/facebook-brands-solid-1.svg\" title=\"facebook-marques-solidaires 1\"\/><\/a>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-b2058832\">\n<h5 class=\"gb-text gb-text-facdcfc1\">\"Une excellente journ\u00e9e d'apprentissage aujourd'hui. L'attention port\u00e9e \u00e0 l'anatomie\/aux marquages et \u00e0 la technique d'injection est sup\u00e9rieure \u00e0 beaucoup d'autres cours. Merci !\"<\/h5>\n\n\n\n<div class=\"gb-element-89516ab4\">\n<div class=\"gb-element-14456e5f\">\n<img loading=\"lazy\" decoding=\"async\" width=\"108\" height=\"122\" class=\"gb-media-1252bd6d\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/Tracey-Ruddick.jpg\" title=\"Tracey-Ruddick\" alt=\"Dr. Tracey Ruddick\"\/>\n\n\n\n<div>\n<h6 class=\"gb-text gb-text-804d3da5\">Dr. Tracey Ruddick (Dentiste)<\/h6>\n\n\n\n<p class=\"gb-text gb-text-bdfec96b\">Canmore, AB<\/p>\n<\/div>\n<\/div>\n\n\n\n<a href=\"#\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"20\" height=\"20\" class=\"gb-media-1bbfa175 image-auto-height-content\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/facebook-brands-solid-1.svg\" title=\"facebook-marques-solidaires 1\"\/><\/a>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-a8238e59\">\n<h5 class=\"gb-text gb-text-8f05d2a0\">\"L'un des meilleurs cours sur le Botox. Je recommande vivement le cours du Dr Roberts, si vous envisagez une carri\u00e8re r\u00e9ussie dans les injections de Botox. Lui et le Dr. Jan sont pleins de connaissances et ils sont d\u00e9sireux de partager leur richesse de savoir.\"<\/h5>\n\n\n\n<div class=\"gb-element-9915537f\">\n<div class=\"gb-element-3a9b21e2\">\n<img loading=\"lazy\" decoding=\"async\" width=\"108\" height=\"116\" class=\"gb-media-0b6feb45\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/Roocha-Vyas.jpg\" title=\"Roocha-Vyas\" alt=\"Dr. Roocha Vyas\"\/>\n\n\n\n<div>\n<h6 class=\"gb-text gb-text-a5a66d73\">Dr. Roocha Vyas (Dentiste)<\/h6>\n\n\n\n<p class=\"gb-text gb-text-1c1f5839\">Thornhill, ON<\/p>\n<\/div>\n<\/div>\n\n\n\n<a href=\"#\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"20\" height=\"20\" class=\"gb-media-1a628128 image-auto-height-content\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/facebook-brands-solid-1.svg\" title=\"facebook-marques-solidaires 1\"\/><\/a>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-ac9a7b05  grid-container\">\n<div class=\"wp-block-group is-vertical is-content-justification-left is-nowrap is-layout-flex wp-container-core-group-is-layout-cfee1719 wp-block-group-is-layout-flex\">\n<div class=\"gb-element-8da68eaa\">\n<div class=\"gb-element-68a6ece7\">\n<h2 class=\"gb-text gb-text-05ef0eef\">La formation PTIFAT <em><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-pt-secondary-color\">Avantage<\/mark><\/em><\/h2>\n<\/div>\n\n\n\n<div class=\"gb-element-6166b982\">\n<div class=\"gb-element-1623a727\">\n<div class=\"gb-element-71ba05d1\">\n<div class=\"gb-element-760da07c\">\n<div class=\"gb-element-75c71084\"><\/div>\n\n\n\n<div class=\"gb-element-35bc22b8\">\n<img loading=\"lazy\" decoding=\"async\" width=\"102\" height=\"34\" class=\"gb-media-16188991\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/Group-25.svg\" title=\"Groupe 25\"\/>\n<\/div>\n\n\n\n<div class=\"gb-element-31062c47\">\n<h6 class=\"gb-text gb-text-b8671a26\">Cours typique de Botox<\/h6>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-729d6bb3\">\n<div class=\"gb-element-c4fb4479\">\n<p class=\"gb-text gb-text-feb8df71\">Heures d'anatomie&nbsp;<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-682ade11\">\n<p class=\"gb-text gb-text-87212dbe\">(+ de 16 h)<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-52d047cb\">\n<p class=\"gb-text gb-text-ef3d770e\">1-2 heures<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-2d795284\">\n<div class=\"gb-element-d114f51d\">\n<p class=\"gb-text gb-text-c1bf3a2f\">Heures d'exp\u00e9rience pratique&nbsp;<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-89baa251\">\n<p class=\"gb-text gb-text-5b0d4512\">(+ de 16 h)<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-c87df779\">\n<p class=\"gb-text gb-text-403e34d3\">4 heures<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-eb101f82\">\n<div class=\"gb-element-c94bde30\">\n<p class=\"gb-text gb-text-9ed20de3\">Nombre d'injections sur mod\u00e8le de patient<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-0f42d711\">\n<p class=\"gb-text gb-text-31005933\">8+<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-87e61b34\">\n<p class=\"gb-text gb-text-21c82092\">Rarement<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-ba20e79c\">\n<div class=\"gb-element-d40e1f12\">\n<p class=\"gb-text gb-text-4db07750\">Formation \u00e0 la photographie<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-48b6a8f6\">\n<img loading=\"lazy\" decoding=\"async\" width=\"25\" height=\"25\" class=\"gb-media-cdaad92a\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/star-mark.svg\" title=\"marque-\u00e9toile\"\/>\n<\/div>\n\n\n\n<div class=\"gb-element-f07c5fe1\">\n<p class=\"gb-text gb-text-00500a26\">Limit\u00e9e<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-5ffc8429\">\n<div class=\"gb-element-0fa1f45b\">\n<p class=\"gb-text gb-text-aab9d936\"><strong>Applications enseign\u00e9es\u00a0: \u00e0 la fois th\u00e9rapeutiques<\/strong> et esth\u00e9tiques<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-803d6eb5\">\n<img loading=\"lazy\" decoding=\"async\" width=\"25\" height=\"25\" class=\"gb-media-556b0ff5\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/star-mark.svg\" title=\"marque-\u00e9toile\"\/>\n<\/div>\n\n\n\n<div class=\"gb-element-ac603857\">\n<img loading=\"lazy\" decoding=\"async\" width=\"25\" height=\"25\" class=\"gb-media-a6864046\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/minus-icon.svg\" title=\"ic\u00f4ne moins\"\/>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-8258c17e\">\n<div class=\"gb-element-79218a3a\">\n<p class=\"gb-text gb-text-4e8233ef\">Pratique de l'int\u00e9gration enseign\u00e9e<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-f5302b96\">\n<img loading=\"lazy\" decoding=\"async\" width=\"25\" height=\"25\" class=\"gb-media-eed17832\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/star-mark.svg\" title=\"marque-\u00e9toile\"\/>\n<\/div>\n\n\n\n<div class=\"gb-element-bf82ecd0\">\n<img loading=\"lazy\" decoding=\"async\" width=\"25\" height=\"25\" class=\"gb-media-863ce4bd\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/minus-icon.svg\" title=\"ic\u00f4ne moins\"\/>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-32716784\">\n<div class=\"gb-element-cd469734\">\n<p class=\"gb-text gb-text-ef72d45c\">Soutien au marketing<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-3e9eb108\">\n<img loading=\"lazy\" decoding=\"async\" width=\"25\" height=\"25\" class=\"gb-media-75c17ed7\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/star-mark.svg\" title=\"marque-\u00e9toile\"\/>\n<\/div>\n\n\n\n<div class=\"gb-element-26b03ce7\">\n<img loading=\"lazy\" decoding=\"async\" width=\"25\" height=\"25\" class=\"gb-media-2daad243\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/minus-icon.svg\" title=\"ic\u00f4ne moins\"\/>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-12800333\">\n<div class=\"gb-element-1cf34618\">\n<p class=\"gb-text gb-text-320cffb3\">Soutien \u00e0 la pratique du suivi<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-e188aad8\">\n<img loading=\"lazy\" decoding=\"async\" width=\"25\" height=\"25\" class=\"gb-media-6cc0dc12\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/star-mark.svg\" title=\"marque-\u00e9toile\"\/>\n<\/div>\n\n\n\n<div class=\"gb-element-ba0888da\">\n<img loading=\"lazy\" decoding=\"async\" width=\"25\" height=\"25\" class=\"gb-media-e6f83fc4\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/minus-icon.svg\" title=\"ic\u00f4ne moins\"\/>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-74622f4f\">\n<div class=\"gb-element-6abcb2f1\">\n<p class=\"gb-text gb-text-a70bb054\">Exp\u00e9rience des enseignants<\/p>\n<\/div>\n\n\n\n<div class=\"gb-element-aff36257\">\n<img loading=\"lazy\" decoding=\"async\" width=\"25\" height=\"25\" class=\"gb-media-3bfc889a\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/star-mark.svg\" title=\"marque-\u00e9toile\"\/>\n<\/div>\n\n\n\n<div class=\"gb-element-4d153b11\">\n<img loading=\"lazy\" decoding=\"async\" width=\"25\" height=\"25\" class=\"gb-media-d995a7b3\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/minus-icon.svg\" title=\"ic\u00f4ne moins\"\/>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"gb-element-000e9c2a\">\n<img loading=\"lazy\" decoding=\"async\" width=\"50\" height=\"71\" class=\"gb-media-bd50bbbb\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/cert.svg\" title=\"certitude\"\/>\n\n\n\n<div class=\"gb-element-ffbb0170\">\n<h5 class=\"gb-text gb-text-2b509cd6\">Nombre <em><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-pt-secondary-color\">canadiennes<\/mark><\/em> de pratique des th\u00e9rapies esth\u00e9tiques du visage<\/h5>\n\n\n\n<p class=\"gb-text gb-text-e51ef975\">Notre formation et nos protocoles cliniques ont \u00e9tabli la norme au Canada et d\u00e9passent toutes les exigences de l'universit\u00e9.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<img loading=\"lazy\" decoding=\"async\" width=\"44\" height=\"94\" class=\"gb-media-a1d168cd\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/section-icon.svg\" title=\"ic\u00f4ne de section\"\/>\n<\/div>\n\n\n\n<h2 class=\"gb-text gb-text-37ab99b5\">Objectifs du cours<\/h2>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Identifier et marquer les rep\u00e8res anatomiques pr\u00e9cis du visage pour placer le Botox de mani\u00e8re esth\u00e9tique dans la partie sup\u00e9rieure du visage.<\/li>\n\n\n\n<li>Identifier et marquer les points de rep\u00e8re anatomiques pr\u00e9cis du visage pour placer le Botox dans les cas de TMD et de douleur myofasciale.<\/li>\n\n\n\n<li>D\u00e9crire la technique et les r\u00e8gles d'injection de la farine de PTIFAT.<\/li>\n<\/ol>\n\n\n\n<h2 class=\"gb-text gb-text-397fef76\">Politique d'enregistrement<\/h2>\n\n\n\n<p>Nous nous engageons \u00e0 vous offrir une exp\u00e9rience \u00e9ducative et clinique sans pr\u00e9c\u00e9dent. Chaque cours a un nombre limit\u00e9 de places et comprend un ratio instructeur\/\u00e9tudiant \u00e9lev\u00e9. Pour y parvenir, nous consacrons une part importante de nos ressources et nous nous engageons aupr\u00e8s des membres de la facult\u00e9, des instructeurs, du personnel clinique, des patients, des lieux, des h\u00f4tels, etc. afin de nous assurer que le cours d\u00e9passe vos attentes.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Tous les paiements sont non remboursables et non transf\u00e9rables, y compris les cours en ligne et les commandes de produits.<\/li>\n\n\n\n<li>L'acc\u00e8s au mat\u00e9riel de cours en ligne est accord\u00e9 pour une dur\u00e9e d'un an \u00e0 compter de l'inscription.<\/li>\n<\/ul>\n\n\n\n<div class=\"gb-element-69663f72\" id=\"full-policy\">\n<h2 class=\"gb-text\">Contenu int\u00e9gral de la politique<\/h2>\n<\/div>\n\n\n\n<p class=\"gb-text small-link see-more\" data-pointer=\"full-policy\"><a href=\"#\">Voir la politique compl\u00e8te  <img loading=\"lazy\" decoding=\"async\" width=\"10\" height=\"6\" class=\"wp-image-1040\" style=\"width: 10px;\" src=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/Group-120.svg\" alt=\"\"><\/a><\/p>\n<\/div>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Un atelier pratique d'une journ\u00e9e pour les praticiens qualifi\u00e9s des niveaux 1 et 2 qui cherchent \u00e0 reprendre confiance en eux apr\u00e8s une interruption des injections. Pratiquez la technique de rep\u00e9rage PTIFAT pour un placement pr\u00e9cis du site d'injection et apprenez \u00e0 incorporer la technique d'injection PTIFAT dans un environnement favorable.<\/p>","protected":false},"featured_media":3116,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[75],"product_tag":[],"class_list":{"0":"post-3041","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-courses","7":"","8":"woocommerce-text-align-center","9":"woocommerce-image-align-center","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-variable"},"exclude_global_add_ons":[],"addons":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Botox Refresher Course for Level 1 &amp; 2 Qualified Practitioners<\/title>\n<meta name=\"description\" content=\"This one-day hands-on workshop is for qualified practitioners seeking to rebuild confidence after having not been injecting recently.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ptifa.com\/fr\/p\/cours\/cours-de-recyclage-botox\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Botox Refresher Course for Level 1 &amp; 2 Qualified Practitioners\" \/>\n<meta property=\"og:description\" content=\"This one-day hands-on workshop is for qualified practitioners seeking to rebuild confidence after having not been injecting recently.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ptifa.com\/fr\/p\/cours\/cours-de-recyclage-botox\/\" \/>\n<meta property=\"og:site_name\" content=\"Pacific Training Institute for Facial Aesthetics &amp; Therapeutics\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-13T21:14:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/Botox-Refresher.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1056\" \/>\n\t<meta property=\"og:image:height\" content=\"752\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data1\" content=\"20 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ptifa.com\\\/fr\\\/p\\\/cours\\\/cours-de-recyclage-botox\\\/\",\"url\":\"https:\\\/\\\/ptifa.com\\\/fr\\\/p\\\/cours\\\/cours-de-recyclage-botox\\\/\",\"name\":\"Botox Refresher Course for Level 1 & 2 Qualified Practitioners\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ptifa.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ptifa.com\\\/fr\\\/p\\\/cours\\\/cours-de-recyclage-botox\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ptifa.com\\\/fr\\\/p\\\/cours\\\/cours-de-recyclage-botox\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ptifa.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Botox-Refresher.webp\",\"datePublished\":\"2025-03-30T00:58:09+00:00\",\"dateModified\":\"2025-07-13T21:14:39+00:00\",\"description\":\"This one-day hands-on workshop is for qualified practitioners seeking to rebuild confidence after having not been injecting recently.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ptifa.com\\\/fr\\\/p\\\/cours\\\/cours-de-recyclage-botox\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ptifa.com\\\/fr\\\/p\\\/cours\\\/cours-de-recyclage-botox\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/ptifa.com\\\/fr\\\/p\\\/cours\\\/cours-de-recyclage-botox\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ptifa.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Botox-Refresher.webp\",\"contentUrl\":\"https:\\\/\\\/ptifa.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Botox-Refresher.webp\",\"width\":1056,\"height\":752,\"caption\":\"A woman marking a man with a green marker planning the injection sites prior to Botox treatment.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ptifa.com\\\/fr\\\/p\\\/cours\\\/cours-de-recyclage-botox\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ptifa.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/ptifa.com\\\/fr\\\/produits\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Botox\u00ae Refresher Course\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ptifa.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ptifa.com\\\/fr\\\/\",\"name\":\"Pacific Training Institute for Facial Aesthetics &amp; Therapeutics\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/ptifa.com\\\/fr\\\/#organization\"},\"alternateName\":\"PTIFAT\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ptifa.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ptifa.com\\\/fr\\\/#organization\",\"name\":\"Pacific Training Institute for Facial Aesthetics & Therapeutics\",\"alternateName\":\"PTIFAT\",\"url\":\"https:\\\/\\\/ptifa.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/ptifa.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ptifa.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/ptifa-logo.svg\",\"contentUrl\":\"https:\\\/\\\/ptifa.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/ptifa-logo.svg\",\"width\":310,\"height\":42,\"caption\":\"Pacific Training Institute for Facial Aesthetics & Therapeutics\"},\"image\":{\"@id\":\"https:\\\/\\\/ptifa.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cours de remise \u00e0 niveau sur le Botox pour les praticiens qualifi\u00e9s de niveau 1 et 2","description":"Cet atelier pratique d'une journ\u00e9e s'adresse aux praticiens qualifi\u00e9s qui cherchent \u00e0 reprendre confiance en eux apr\u00e8s une p\u00e9riode d'inactivit\u00e9.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ptifa.com\/fr\/p\/cours\/cours-de-recyclage-botox\/","og_locale":"fr_CA","og_type":"article","og_title":"Botox Refresher Course for Level 1 & 2 Qualified Practitioners","og_description":"This one-day hands-on workshop is for qualified practitioners seeking to rebuild confidence after having not been injecting recently.","og_url":"https:\/\/ptifa.com\/fr\/p\/cours\/cours-de-recyclage-botox\/","og_site_name":"Pacific Training Institute for Facial Aesthetics &amp; Therapeutics","article_modified_time":"2025-07-13T21:14:39+00:00","og_image":[{"width":1056,"height":752,"url":"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/Botox-Refresher.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimation du temps de lecture":"20 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ptifa.com\/fr\/p\/cours\/cours-de-recyclage-botox\/","url":"https:\/\/ptifa.com\/fr\/p\/cours\/cours-de-recyclage-botox\/","name":"Cours de remise \u00e0 niveau sur le Botox pour les praticiens qualifi\u00e9s de niveau 1 et 2","isPartOf":{"@id":"https:\/\/ptifa.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ptifa.com\/fr\/p\/cours\/cours-de-recyclage-botox\/#primaryimage"},"image":{"@id":"https:\/\/ptifa.com\/fr\/p\/cours\/cours-de-recyclage-botox\/#primaryimage"},"thumbnailUrl":"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/Botox-Refresher.webp","datePublished":"2025-03-30T00:58:09+00:00","dateModified":"2025-07-13T21:14:39+00:00","description":"Cet atelier pratique d'une journ\u00e9e s'adresse aux praticiens qualifi\u00e9s qui cherchent \u00e0 reprendre confiance en eux apr\u00e8s une p\u00e9riode d'inactivit\u00e9.","breadcrumb":{"@id":"https:\/\/ptifa.com\/fr\/p\/cours\/cours-de-recyclage-botox\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ptifa.com\/fr\/p\/cours\/cours-de-recyclage-botox\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/ptifa.com\/fr\/p\/cours\/cours-de-recyclage-botox\/#primaryimage","url":"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/Botox-Refresher.webp","contentUrl":"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/03\/Botox-Refresher.webp","width":1056,"height":752,"caption":"A woman marking a man with a green marker planning the injection sites prior to Botox treatment."},{"@type":"BreadcrumbList","@id":"https:\/\/ptifa.com\/fr\/p\/cours\/cours-de-recyclage-botox\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ptifa.com\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/ptifa.com\/fr\/produits\/"},{"@type":"ListItem","position":3,"name":"Botox\u00ae Refresher Course"}]},{"@type":"WebSite","@id":"https:\/\/ptifa.com\/fr\/#website","url":"https:\/\/ptifa.com\/fr\/","name":"Institut de formation du Pacifique pour l'esth\u00e9tique faciale et la th\u00e9rapeutique","description":"","publisher":{"@id":"https:\/\/ptifa.com\/fr\/#organization"},"alternateName":"PTIFAT","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ptifa.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/ptifa.com\/fr\/#organization","name":"Institut de formation du Pacifique pour l'esth\u00e9tique faciale et la th\u00e9rapeutique","alternateName":"PTIFAT","url":"https:\/\/ptifa.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/ptifa.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/ptifa-logo.svg","contentUrl":"https:\/\/ptifa.com\/wp-content\/uploads\/2025\/02\/ptifa-logo.svg","width":310,"height":42,"caption":"Pacific Training Institute for Facial Aesthetics & Therapeutics"},"image":{"@id":"https:\/\/ptifa.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/ptifa.com\/fr\/wp-json\/wp\/v2\/product\/3041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ptifa.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ptifa.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ptifa.com\/fr\/wp-json\/wp\/v2\/media\/3116"}],"wp:attachment":[{"href":"https:\/\/ptifa.com\/fr\/wp-json\/wp\/v2\/media?parent=3041"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ptifa.com\/fr\/wp-json\/wp\/v2\/product_brand?post=3041"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ptifa.com\/fr\/wp-json\/wp\/v2\/product_cat?post=3041"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ptifa.com\/fr\/wp-json\/wp\/v2\/product_tag?post=3041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}